{"id":24,"count":1,"description":"","link":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/","name":"digital assets","slug":"digital-assets","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>digital assets Archive - ZHAW Wealth Management Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"digital assets Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/\" \/>\n<meta property=\"og:site_name\" content=\"ZHAW Wealth Management Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/tag\\\/digital-assets\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/tag\\\/digital-assets\\\/\",\"name\":\"digital assets Archive - ZHAW Wealth Management Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/tag\\\/digital-assets\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/tag\\\/digital-assets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"digital assets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/\",\"name\":\"ZHAW Wealth Management Blog\",\"description\":\"A Blog of the ZHAW Zurich University of Applied Sciences\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#organization\",\"name\":\"ZHAW Wealth Management Blog\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/files\\\/2024\\\/03\\\/cropped-zhaw-logo.png\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/files\\\/2024\\\/03\\\/cropped-zhaw-logo.png\",\"width\":199,\"height\":209,\"caption\":\"ZHAW Wealth Management Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/wealth-management\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"digital assets Archive - ZHAW Wealth Management Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/","og_locale":"en_US","og_type":"article","og_title":"digital assets Archive","og_url":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/","og_site_name":"ZHAW Wealth Management Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/","url":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/","name":"digital assets Archive - ZHAW Wealth Management Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#website"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/wealth-management\/tag\/digital-assets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/wealth-management\/"},{"@type":"ListItem","position":2,"name":"digital assets"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#website","url":"https:\/\/blog.zhaw.ch\/wealth-management\/","name":"ZHAW Wealth Management Blog","description":"A Blog of the ZHAW Zurich University of Applied Sciences","publisher":{"@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/wealth-management\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#organization","name":"ZHAW Wealth Management Blog","url":"https:\/\/blog.zhaw.ch\/wealth-management\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#\/schema\/logo\/image\/","url":"https:\/\/blog.zhaw.ch\/wealth-management\/files\/2024\/03\/cropped-zhaw-logo.png","contentUrl":"https:\/\/blog.zhaw.ch\/wealth-management\/files\/2024\/03\/cropped-zhaw-logo.png","width":199,"height":209,"caption":"ZHAW Wealth Management Blog"},"image":{"@id":"https:\/\/blog.zhaw.ch\/wealth-management\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/wealth-management\/wp-json\/wp\/v2\/tags\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/wealth-management\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/wealth-management\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.zhaw.ch\/wealth-management\/wp-json\/wp\/v2\/posts?tags=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}