{"id":26,"count":2,"description":"","link":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/","name":"CAS Schwammstadt","slug":"cas-schwammstadt","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CAS Schwammstadt-Archiv - Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAS Schwammstadt-Archiv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/\" \/>\n<meta property=\"og:site_name\" content=\"Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/tag\\\/cas-schwammstadt\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/tag\\\/cas-schwammstadt\\\/\",\"name\":\"CAS Schwammstadt-Archiv - Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/tag\\\/cas-schwammstadt\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/tag\\\/cas-schwammstadt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAS Schwammstadt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/\",\"name\":\"Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/natuerlich\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CAS Schwammstadt-Archiv - Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/","og_locale":"de_DE","og_type":"article","og_title":"CAS Schwammstadt-Archiv","og_url":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/","og_site_name":"Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/","url":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/","name":"CAS Schwammstadt-Archiv - Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/natuerlich\/#website"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/natuerlich\/tag\/cas-schwammstadt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/blog.zhaw.ch\/natuerlich\/"},{"@type":"ListItem","position":2,"name":"CAS Schwammstadt"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/natuerlich\/#website","url":"https:\/\/blog.zhaw.ch\/natuerlich\/","name":"Nat\u00fcrlich \u2013 Lernen. Forschen. Morgen gestalten.","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/natuerlich\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/natuerlich\/wp-json\/wp\/v2\/tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/natuerlich\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/natuerlich\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.zhaw.ch\/natuerlich\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}