{"id":9116,"date":"2017-07-04T06:34:13","date_gmt":"2017-07-04T04:34:13","guid":{"rendered":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?p=9116"},"modified":"2017-07-04T06:34:13","modified_gmt":"2017-07-04T04:34:13","slug":"zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/","title":{"rendered":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament"},"content":{"rendered":"<p><em>Die Beziehung von Marketingmenschen und Agenturen ist nicht immer von Harmonie gepr\u00e4gt. Da treffen kreative Ideen auch mal auf Widerstand und k\u00f6nnen nicht so umgesetzt werden, wie es notwendig gewesen w\u00e4re. Die Z\u00fcrcher Agentur <\/em><a href=\"http:\/\/www.walker.ag\/\"><em>Walker<\/em><\/a><em> zeigt, dass es auch anders geht. Sie tritt immer wieder mit aussergew\u00f6hnlichen Ideen in Erscheinung und hat nun f\u00fcr den Online-Personalvermittler <\/em><a href=\"https:\/\/www.coople.com\/ch\/\"><em>Coople<\/em><\/a><em> ein ganz spezielles Mailing entwickelt. \u00c4usserst liebevoll gestaltete Mini-Mitarbeiter werden als Pillen in ein Blister eingeschweisst und nat\u00fcrlich mit Vitamin B versehen. Dieses Mailing ist das ideale Medikament gegen den Mitarbeitermangel. Stefanie Huber von <\/em><a href=\"http:\/\/www.walker.ag\/\"><em>Walker<\/em><\/a><em> erkl\u00e4rt, wie man auf so eine Idee kommt.<\/em><\/p>\n<p><strong>Frau Huber, Ihr Kunde <\/strong><a href=\"https:\/\/www.coople.com\/ch\/\"><strong>Coople<\/strong><\/a><strong> hatte seine Buchungsplattform \u00fcberarbeitet und ein Rebranding umgesetzt. Wie kamen Sie auf die Idee mit den Arbeitskr\u00e4ften als Medikament? <\/strong><\/p>\n<p>Eine Idee ist immer dann besonders stark, wenn man etwas Relevantes \u00fcber das Produkt oder die Dienstleistung erz\u00e4hlen kann und sich die Zielgruppe angesprochen f\u00fchlt. <a href=\"https:\/\/www.coople.com\/ch\/\">Coople<\/a> ist ein Dienstleistungsunternehmen, welches Unternehmen in kurzer Zeit (zu 98% in unter 4 Stunden) mit flexiblen Arbeitskr\u00e4ften verbindet. Dies ist ein starker USP, den wir als Sprungbrett zur Ideenfindung genommen haben. Auch hilft es, sich in der Kreationsphase in die Zielgruppe hineinzuversetzen, dies hat dann in diesem Fall auch zur Idee gef\u00fchrt; Wenn man dringend Personal braucht ist das nat\u00fcrlich kein gutes Gef\u00fchl, man ist sehr gestresst, da man f\u00fcr 2 oder 3 Personen arbeiten muss. Das sp\u00fcrt man, vor allem im Service oder im Gesundheitswesen, dann auch k\u00f6rperlich. <a href=\"https:\/\/www.coople.com\/ch\/\">Coople<\/a> ist wie die Erl\u00f6sung von diesen \u201eArbeitsschmerzen\u201c, da innerhalb von kurzer Zeit eine Wirkung in Form von zus\u00e4tzlichem Personal eintrifft. Ein Medikament gegen Mitarbeitermangel sozusagen.<\/p>\n<figure id=\"attachment_9117\" aria-describedby=\"caption-attachment-9117\" style=\"width: 584px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9117 size-large\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein-1024x683.jpg\" alt=\"\" width=\"584\" height=\"390\"><\/a><figcaption id=\"caption-attachment-9117\" class=\"wp-caption-text\">Eine innovative Idee mit einer speziellen Umsetzung, Mitarbeiter in Blister Form \u00a9 Walker\/Coople<\/figcaption><\/figure>\n<p><strong>Wie war die erste Reaktion von <\/strong><a href=\"https:\/\/www.coople.com\/ch\/\"><strong>Coople<\/strong><\/a><strong>? Mussten Sie viel \u00dcberzeugungsarbeit leisten, oder bekamen Sie schnell ein gr\u00fcnes Licht?<\/strong><\/p>\n<p>Wir mussten praktisch keine \u00dcberzeugungsarbeit leisten. Dem Kunden hat die Idee sofort gefallen, da sie einfach und auf dem Punkt ist. Er hat das kreative Potential erkannt, sich mit dieser Idee vom Wettbewerb abzusetzen und aufzufallen.<\/p>\n<p><strong>Gerade im Marketing, sind die kreativen Ideen nat\u00fcrlich enorm wichtig. Dennoch scheitert es oft an der Umsetzung. Wie haben Sie diese Idee schlussendlich realisiert? Das Mailing sieht ja wirklich wie ein Medikament aus, da haben die Druckpartner sicherlich einmal leer geschluckt\u2026<\/strong><\/p>\n<p>Da haben Sie Recht, hinter diesem Mailing steckt eine lange und aufw\u00e4ndige Recherchearbeit nach Druckpartnern, welche das Know-How, den Willen und die M\u00f6glichkeiten haben, etwas Neues zu versuchen und einen Schritt weiter zu gehen. Bisher haben wir aber fast immer die Erfahrung gemacht, dass sich der Glaube an die gute Idee und der Einsatz daf\u00fcr am Ende auszahlt. Man sollte sich nicht von den ersten H\u00fcrden aufhalten lassen. Am Ende haben wir einen Druckpartner gefunden, der die Idee so gut fand, dass er in Eigenregie mit seinen Druckmaschinen Tests gemacht und sich Halterungen gebaut hat, um die Pillen maximal bedrucken zu k\u00f6nnen. Die bedruckten Arznei-Kapseln wurden dann von einem anderen Partner maschinell verblistert und verpackt.<\/p>\n<figure id=\"attachment_9118\" aria-describedby=\"caption-attachment-9118\" style=\"width: 584px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/IMG_5528.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-9118\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/IMG_5528-1024x683.jpg\" alt=\"\" width=\"584\" height=\"390\"><\/a><figcaption id=\"caption-attachment-9118\" class=\"wp-caption-text\">Schwierige Umsetzung f\u00fcr die Druckpartner, aber am Ende doch erfolgreich \u00a9 Walker\/Coople<\/figcaption><\/figure>\n<p><strong>Haben Sie schon erste Reaktionen auf das Mailing erhalten?<\/strong><\/p>\n<p>Ja, die Reaktionen sind sehr gut. Das Mailing f\u00e4llt auf und wir haben bereits Anfragen von anderen Unternehmen bekommen, die ebenfalls ein solches Mailing haben m\u00f6chten.<\/p>\n<p>Nat\u00fcrlich gibt es, vor allem bei kreativen Massnahmen, immer auch einige kritische Meinungen, jedoch \u00fcberwiegen die Positiven deutlich.<\/p>\n<p><strong>Gerade in der heutigen Zeit ist es wichtig, dass man aus der Masse heraussticht. Woher nehmen Sie die Kreativit\u00e4t und wie arbeiten Sie mit Ihren Kunden zusammen?<\/strong><\/p>\n<p>Wir alle werden tagt\u00e4glich mit tausenden von Werbebotschaften bombardiert, darum ist es wichtig aufzufallen. Und das am besten so, dass die Botschaft auch mit der Marke verkn\u00fcpft und somit nicht austauschbar wird. Dies kann man erreichen, wenn man \u00fcber lange Zeit viel Geld in andauernde Medienpr\u00e4senz investiert. Da die Marketingbudgets in der heutigen Zeit aber immer kleiner werden, ist eine gute Idee der effizienteste und g\u00fcnstigste Weg mehr Reichweite zu erlangen. Je besser die Idee desto weniger Zeit und Geld sind n\u00f6tig, um eine Wirkung zu erzielen.<\/p>\n<p>Uns ist es wichtig eng mit unseren Kunden zusammen zu arbeiten, denn die Basis einer guten Kampagne ist ein guter Dialog mit Wissensaustausch. Bevor wir mit der Ideenfindung beginnen, erarbeiten wir zun\u00e4chst eine Strategie, die auf den Inputs unserer Kunden, deren Mitarbeitern und deren Kunden basiert. Dieses Wissen fliesst dann in die Kampagnenentwicklung ein, mit dem Ziel aus dem Produkt heraus eine effiziente Kampagne zu entwickeln und diese zielgruppengerecht f\u00fcr die einzelnen Kan\u00e4le umzusetzen.<\/p>\n<p>Die Kreativit\u00e4t zu den Kampagnen kommt beim Machen. Es ist eine Mischung aus Spielen, Ausprobieren und Grenzen testen. Ich arbeite meistens so, dass ich anhand des Briefings zu den jeweiligen Themen eine Recherche mache und voll in das Produkt oder die Dienstleistung und die Zielgruppe eintauche. Dann lasse ich das alles gehen und spiele mit dem Thema in verschiedenste Richtungen. Daraus entwickeln sich dann die einzelnen Ideenrichtungen. Wenn eine Idee richtig gut ist, sp\u00fcre ich das an einem Kribbeln im Bauch.<\/p>\n<figure id=\"attachment_9119\" aria-describedby=\"caption-attachment-9119\" style=\"width: 584px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Pillen_gruppe_klein.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9119 size-large\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Pillen_gruppe_klein-1024x683.jpg\" alt=\"\" width=\"584\" height=\"390\"><\/a><figcaption id=\"caption-attachment-9119\" class=\"wp-caption-text\">Es gilt aus der Masse herauszustechen \u00a9 Walker\/Coople<\/figcaption><\/figure>\n<p><strong>Wo sehen Sie die Stolpersteine in der Zusammenarbeit?<\/strong><\/p>\n<p>Um aus der Masse herauszustechen, ist es manchmal notwendig etwas ganz Neues zu wagen. Dies erfordert Mut, Entscheidungswille und vor allem auch Vertrauen.<\/p>\n<p>Gerade in Unternehmen mit vielen Entscheidern am Tisch hat es eine Idee, die neu ist und noch nicht gesehen wurde, leider oft schwer, da sie es allen recht machen muss. Und eine solche Idee ist meistens nicht neu und mutig.<\/p>\n<p>Ich denke gute Kommunikation von beiden Seiten ist daher das A und O, denn viel zu oft entstehen Missverst\u00e4ndnisse, die h\u00e4tten vermieden werden k\u00f6nnen. Dies funktioniert je besser, je partnerschaftlicher die Beziehung gesehen wird. Ausserdem sollten die Anspr\u00fcche an die Kommunikationsl\u00f6sung, das Timing und Vorstellungen im Vorhinein gut definiert werden, damit man gemeinsam an einem Strang ziehen kann.<\/p>\n<p><strong>Wenn Sie, aus Agentursicht, angehenden Marketingfachleuten einen Tipp geben k\u00f6nnten, was w\u00fcrden Sie raten?<\/strong><\/p>\n<p>Mutig zu sein und auch seinem Bauchgef\u00fchl zu vertrauen und nicht nur rationalen Measuring-Tools. Denn der emotionale Faktor, den eine gute Idee transportiert, ob sie zum Weinen oder Lachen bringt, sollte nicht untersch\u00e4tzt werden.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.walker.ag\/\">http:\/\/www.walker.ag\/<\/a><\/p>\n<p><a href=\"https:\/\/www.coople.com\/ch\/\">https:\/\/www.coople.com\/ch\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/agentur\/\">Agentur<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/arbeitskraefte\/\">Arbeitskr\u00e4fte<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/arbeitsschmerzen\/\">Arbeitsschmerzen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/arznei-kapseln\/\">Arznei-Kapseln<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/blister\/\">Blister<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/coople\/\">Coople<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/druckerei\/\">Druckerei<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/idee\/\">Idee<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/imm\/\">IMM<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/institut-fur-marketing-management\/\">Institut f\u00fcr Marketing Management<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/kampagne\/\">Kampagne<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/kommunikation\/\">Kommunikation<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/mailing\/\">Mailing<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/measuring-tools\/\">Measuring-Tools<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/medienpraesenz\/\">Medienpr\u00e4senz<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/mini-mitarbeiter\/\">Mini-Mitarbeiter<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/personalvermittler\/\">Personalvermittler<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/pillen\/\">Pillen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/recherche\/\">Recherche<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/stefanie-huber\/\">Stefanie Huber<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/umsetzung\/\">Umsetzung<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/verblistern\/\">verblistern<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/walker\/\">Walker<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/werbebotschaft\/\">Werbebotschaft<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/zielgruppe\/\">Zielgruppe<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/zuercher\/\">Z\u00fcrcher<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Beziehung von Marketingmenschen und Agenturen ist nicht immer von Harmonie gepr\u00e4gt. Da treffen kreative Ideen auch mal auf Widerstand und k\u00f6nnen nicht so umgesetzt werden, wie es notwendig gewesen w\u00e4re. Die Z\u00fcrcher Agentur Walker zeigt, dass es auch anders geht. Sie tritt immer wieder mit aussergew\u00f6hnlichen Ideen in Erscheinung und hat nun f\u00fcr den [&hellip;]<\/p>\n","protected":false},"author":312,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,855],"tags":[1573,1582,1583,1586,1580,1575,1584,1591,246,255,1440,284,1577,1592,1589,1578,1576,1579,1590,1581,1585,1587,1574,1588,1219,1536],"features":[],"class_list":["post-9116","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-dialog-marketing","tag-agentur","tag-arbeitskraefte","tag-arbeitsschmerzen","tag-arznei-kapseln","tag-blister","tag-coople","tag-druckerei","tag-idee","tag-imm","tag-institut-fur-marketing-management","tag-kampagne","tag-kommunikation","tag-mailing","tag-measuring-tools","tag-medienpraesenz","tag-mini-mitarbeiter","tag-personalvermittler","tag-pillen","tag-recherche","tag-stefanie-huber","tag-umsetzung","tag-verblistern","tag-walker","tag-werbebotschaft","tag-zielgruppe","tag-zuercher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament - Marketing Management-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament\" \/>\n<meta property=\"og:description\" content=\"Die Beziehung von Marketingmenschen und Agenturen ist nicht immer von Harmonie gepr\u00e4gt. Da treffen kreative Ideen auch mal auf Widerstand und k\u00f6nnen nicht so umgesetzt werden, wie es notwendig gewesen w\u00e4re. Die Z\u00fcrcher Agentur Walker zeigt, dass es auch anders geht. Sie tritt immer wieder mit aussergew\u00f6hnlichen Ideen in Erscheinung und hat nun f\u00fcr den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing Management-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-04T04:34:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"suva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"suva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/\"},\"author\":{\"name\":\"suva\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\"},\"headline\":\"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament\",\"datePublished\":\"2017-07-04T04:34:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/\"},\"wordCount\":1096,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2017\\\/06\\\/Packaging_v4_klein-1024x683.jpg\",\"keywords\":[\"Agentur\",\"Arbeitskr\u00e4fte\",\"Arbeitsschmerzen\",\"Arznei-Kapseln\",\"Blister\",\"Coople\",\"Druckerei\",\"Idee\",\"IMM\",\"Institut f\u00fcr Marketing Management\",\"Kampagne\",\"Kommunikation\",\"Mailing\",\"Measuring-Tools\",\"Medienpr\u00e4senz\",\"Mini-Mitarbeiter\",\"Personalvermittler\",\"Pillen\",\"Recherche\",\"Stefanie Huber\",\"Umsetzung\",\"verblistern\",\"Walker\",\"Werbebotschaft\",\"Zielgruppe\",\"Z\u00fcrcher\"],\"articleSection\":{\"1\":\"Dialog Marketing\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/\",\"name\":\"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament - Marketing Management-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2017\\\/06\\\/Packaging_v4_klein-1024x683.jpg\",\"datePublished\":\"2017-07-04T04:34:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\",\"name\":\"Marketing Management-Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\",\"name\":\"suva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"caption\":\"suva\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/author\\\/suva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament - Marketing Management-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/","og_locale":"de_DE","og_type":"article","og_title":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament","og_description":"Die Beziehung von Marketingmenschen und Agenturen ist nicht immer von Harmonie gepr\u00e4gt. Da treffen kreative Ideen auch mal auf Widerstand und k\u00f6nnen nicht so umgesetzt werden, wie es notwendig gewesen w\u00e4re. Die Z\u00fcrcher Agentur Walker zeigt, dass es auch anders geht. Sie tritt immer wieder mit aussergew\u00f6hnlichen Ideen in Erscheinung und hat nun f\u00fcr den [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/","og_site_name":"Marketing Management-Blog","article_published_time":"2017-07-04T04:34:13+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein-1024x683.jpg","type":"","width":"","height":""}],"author":"suva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"suva","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/"},"author":{"name":"suva","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3"},"headline":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament","datePublished":"2017-07-04T04:34:13+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/"},"wordCount":1096,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein-1024x683.jpg","keywords":["Agentur","Arbeitskr\u00e4fte","Arbeitsschmerzen","Arznei-Kapseln","Blister","Coople","Druckerei","Idee","IMM","Institut f\u00fcr Marketing Management","Kampagne","Kommunikation","Mailing","Measuring-Tools","Medienpr\u00e4senz","Mini-Mitarbeiter","Personalvermittler","Pillen","Recherche","Stefanie Huber","Umsetzung","verblistern","Walker","Werbebotschaft","Zielgruppe","Z\u00fcrcher"],"articleSection":{"1":"Dialog Marketing"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/","name":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament - Marketing Management-Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2017\/06\/Packaging_v4_klein-1024x683.jpg","datePublished":"2017-07-04T04:34:13+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/zuendende-idee-der-agentur-walker-mitarbeiter-als-medikament\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/marketingmanagement\/"},{"@type":"ListItem","position":2,"name":"Z\u00fcndende Idee der Agentur Walker: Mitarbeiter als Medikament"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/","name":"Marketing Management-Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3","name":"suva","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","caption":"suva"},"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/author\/suva\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/9116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/comments?post=9116"}],"version-history":[{"count":1,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/9116\/revisions"}],"predecessor-version":[{"id":9120,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/9116\/revisions\/9120"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/media?parent=9116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/categories?post=9116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/tags?post=9116"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/features?post=9116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}