{"id":7570,"date":"2015-03-26T10:15:32","date_gmt":"2015-03-26T08:15:32","guid":{"rendered":"http:\/\/blog.zhaw.ch\/marketingmanagement\/?p=7570"},"modified":"2015-06-16T14:00:57","modified_gmt":"2015-06-16T12:00:57","slug":"sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/","title":{"rendered":"Sportvereine &#8211; Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?"},"content":{"rendered":"<p>\u00abAlso wenn di\u00e4 eso spielet, isches ja keis Wunder, dass niemer meh gaht gu luege!\u00bb, ist eine viel geh\u00f6rte Aussage. Doch kommt es nur auf den sportlichen Erfolg an? Wenn ja, wie kann dann ein Verein wie der<a href=\"http:\/\/www.fcstpauli.com\/home\/news\" target=\"_blank\"> FC St. Pauli <\/a>einen Zuschauerschnitt von 96% verzeichnen, obwohl der Klub in der 2. Liga gegen den Abstieg spielt?<\/p>\n<p>Generell gilt zu sagen: Je gr\u00f6sser die Dienstleistungsqualit\u00e4t ist, desto zufriedener ist der Kunde bzw. der Fan. Dies besagt unter anderem die \u00abService-Profit Chain\u00bb, welche den positiven Zusammenhang dieser Faktoren zeigt und als Kreislauf verstanden werden kann. Durch die Verbesserung der Dienstleistungsqualit\u00e4t wird die Kundenzufriedenheit und \u2013loyalit\u00e4t erh\u00f6ht, was wiederum den Gewinn und Wachstum des Unternehmens vergr\u00f6ssert. Dies beeinflusst die Mitarbeiterzufriedenheit und \u2013loyalit\u00e4t, wodurch die Dienstleistungsqualit\u00e4t steigt. Der FC St. Pauli hat eindr\u00fccklich bewiesen, wie wirtschaftlich effektiv eine stringente Marketingstrategie bei sportlicher Unstetigkeit sein kann. Der Verein stieg im Zeitraum von 1995 bis 2004 von der<br \/>\n1. Bundesliga bis in die Regionalliga ab, wobei sich in der gleichen Periode die Merchandising-Ums\u00e4tze des Vereins nahezu vervierfacht haben.<\/p>\n<figure id=\"attachment_7657\" aria-describedby=\"caption-attachment-7657\" style=\"width: 540px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7657 size-full\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg\" alt=\"St. Pauli\" width=\"540\" height=\"304\" \/><\/a><figcaption id=\"caption-attachment-7657\" class=\"wp-caption-text\">Bildquelle: www.zeit.de<\/figcaption><\/figure>\n<p>Ohne Frage ist der sportliche Erfolg auch ein Teil der Dienstleistung eines Sportvereins an den Fan, denn auch die sportliche Leistung der Mannschaft ist ein Qualit\u00e4tssiegel. Aber das sportliche Ergebnis ist nicht die einzig relevante Komponente. Viele andere Bereiche z\u00e4hlen zu den Dienstleistungen eines Klubs dazu, n\u00e4mlich all diejenigen Bereiche, bei welchen die Clubs in direktem Kontakt mit den Fans stehen. Also in den Bereichen Ticketing, Merchandising, Stadion, Vereinsmanagement und Gastronomie. Das <a href=\"http:\/\/imm.zhaw.ch\/de.html\" target=\"_blank\">Institut f\u00fcr Marketing Management <\/a>hat in der <a href=\"http:\/\/www.sfl.ch\/\" target=\"_blank\">Raiffeisen Super League <\/a>die Zufriedenheit der Fans mit ihrem Lieblingsklub anhand der genannten Bereiche untersucht &#8211; <a href=\"http:\/\/www.20min.ch\/sport\/dossier\/superleague\/story\/Fussballfans-waehlen-FCB-zum-Klub-aller-Klubs-16912514\" target=\"_blank\">20 Minuten hat dar\u00fcber berichtet <\/a>.<\/p>\n<p>Das <a href=\"http:\/\/imm.zhaw.ch\/de.html\" target=\"_blank\">IMM<\/a> untersuchte bspw. wie zufrieden die Fans mit der Anfahrt zum Stadion, der Qualit\u00e4t der Speisen und Getr\u00e4nken im Stadion oder mit Ihrem Ticketkauf sind, um nur einige wenige Beispiele zu nennen. Auffallend ist, dass nicht alleine der sportliche Erfolg das Ausschlaggebende f\u00fcr die Zufriedenheit der Fans ist. Lediglich der FC Basel und FC Sion schnitten bei der Umfrage exakt gleich ab, wie die Klubs in der Tabelle der Raiffeisen Super League stehen. Einige in der Liga sportlich erfolgreiche Vereine fanden sich im Ranking weiter hinten. Vor allem die Z\u00fcrcher Vereine schnitten weit hinter ihrer sportlichen Platzierung ab. Der Grasshoppers Club Z\u00fcrich ist nun allerdings bestrebt, Investitionen zu t\u00e4tigen, um den Fans eine h\u00f6here Qualit\u00e4t in der Dienstleistung zu bieten und so die Kundenzufriedenheit zu steigern. Zusammen mit dem IMM suchen die Verantwortlichen Wege, um das Problem zu l\u00f6sen und die Fans zufrieden zu stellen. Andere Vereine konnten hingegen mit einem positiven Ergebnis \u00fcberzeugen, welches den sportlichen Erfolg \u00fcbertrifft. Der FC St. Gallen und FC Thun legten zwei Pl\u00e4tze zu und liessen den finanziell starken BSC Young Boys, welcher insgesamt einen Platz verlor, hinter sich. Auch der FC Vaduz und FC Aarau, die Vereine mit den kleinsten Budgets der Liga, und der FC Luzern stehen im Ranking zwei Pl\u00e4tze besser da als in der Raiffeisen Super League Tabelle.<br \/>\nAuffallend ist das Verh\u00e4ltnis zwischen Kundenzufriedenheit und Budget. Die Vereine mit den f\u00fcnf kleinsten Budgets standen im Ranking der Fanzufriedenheit besser da als in der Liga. Zugleich konnten nur zwei der f\u00fcnf finanziell st\u00e4rksten Vereine die gleiche Position einnehmen, wobei kein Klub mit grossem Budget Pl\u00e4tze gutmachen konnte.<\/p>\n<p>Im Sportmarketing gibt es viele M\u00f6glichkeiten um die Kundenzufriedenheit zu steigern. Im Ausland findet man einige emotionale Massnahmen, welche die Fans begeistern. Ein bekanntes Beispiel hierf\u00fcr ist in der <a href=\"http:\/\/www.nfl.com\/\" target=\"_blank\">National Football League (NFL)<\/a> zu finden. Die Inszenierung des grossen Saisonfinals ist einzigartig und den Fans wird nebst dem sportlichen Ereignis ein grosses Spektakel geboten. Dies zeigt sich unter anderem bei der Halbzeitshow des Super Bowls inklusive einzigartiger Performance eines internationalen Musikstars. Auch in der <a href=\"http:\/\/www.nba.com\/\" target=\"_blank\">NBA<\/a> spielen Emotionen eine grosse Rolle: Beispielsweise werden Fansmit der aus Hollywood-Filmen ber\u00fchmten \u00ab<a href=\"https:\/\/www.youtube.com\/watch?v=51T3BX4-e60\" target=\"_blank\">Kiss Cam<\/a>\u00bb in Szene gesetzt, was immer wieder f\u00fcr tolle Stimmung im Stadion sorgt. Ein anderes, etwas weniger spektakul\u00e4res Beispiel findet sich in der Bundesliga beim FC Bayern: Dieser bietet den Fans eine sogenannte \u00abErlebniswelt\u00bb an, in welcher Sie den Klub n\u00e4her kennen lernen k\u00f6nnen.<\/p>\n<p><span lang=\"DE\" style=\"line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\"><span style=\"color: #000000\">Bei Fragen zum Themengebiet Sport Marketing k\u00f6nnen Sie sich gerne an Marcel H\u00fcttermann, Wissenschaftlicher Mitarbeiter und Programm Manager des <\/span><\/span><span lang=\"DE\"><a href=\"http:\/\/www.weiterbildung.zhaw.ch\/de\/school-of-management-and-law\/programm\/cas-sport-marketing.html\" target=\"_blank\"><span style=\"line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\"><span style=\"text-decoration: underline\"><span style=\"color: #0000ff\">CAS Sport Marketing<\/span><\/span><\/span><\/a><\/span><span lang=\"DE\" style=\"color: #373737;line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\">, <\/span><span lang=\"DE\" style=\"line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\"><span style=\"color: #000000\">unter\u00a0<\/span><\/span><span lang=\"DE\"><a href=\"mailto:marcel.huettermann@zhaw.ch\"><span style=\"line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\"><span style=\"text-decoration: underline\"><span style=\"color: #0000ff\">marcel.huettermann@zhaw.ch<\/span><\/span><\/span><\/a><\/span> <span lang=\"DE\" style=\"line-height: 115%;font-family: 'Arial','sans-serif';font-size: 11.5pt\"><span style=\"color: #000000\">wenden.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/budget\/\">Budget<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/dienstleistung\/\">Dienstleistung<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/fanzufriedenheit\/\">Fanzufriedenheit<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/fc-bayern\/\">FC Bayern<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/fc-st-pauli\/\">FC St. Pauli<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/nba\/\">NBA<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/newsletter\/\">Newsletter<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/newsletter-12015\/\">Newsletter 1\/2015<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/nfl\/\">NFL<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/raiffeisen-super-league\/\">Raiffeisen Super League<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/service-profit-chain\/\">Service-Profit-Chain<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/sportmarketing\/\">Sportmarketing<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00abAlso wenn di\u00e4 eso spielet, isches ja keis Wunder, dass niemer meh gaht gu luege!\u00bb, ist eine viel geh\u00f6rte Aussage. Doch kommt es nur auf den sportlichen Erfolg an? Wenn ja, wie kann dann ein Verein wie der FC St. Pauli einen Zuschauerschnitt von 96% verzeichnen, obwohl der Klub in der 2. Liga gegen den [&hellip;]<\/p>\n","protected":false},"author":171,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,5,8,852],"tags":[794,792,769,798,795,796,900,813,797,793,788,532],"features":[],"class_list":["post-7570","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-dienstleistung","category-marketing-management","category-sport-marketing","tag-budget","tag-dienstleistung","tag-fanzufriedenheit","tag-fc-bayern","tag-fc-st-pauli","tag-nba","tag-newsletter","tag-newsletter-12015","tag-nfl","tag-raiffeisen-super-league","tag-service-profit-chain","tag-sportmarketing"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit? - Marketing Management-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?\" \/>\n<meta property=\"og:description\" content=\"\u00abAlso wenn di\u00e4 eso spielet, isches ja keis Wunder, dass niemer meh gaht gu luege!\u00bb, ist eine viel geh\u00f6rte Aussage. Doch kommt es nur auf den sportlichen Erfolg an? Wenn ja, wie kann dann ein Verein wie der FC St. Pauli einen Zuschauerschnitt von 96% verzeichnen, obwohl der Klub in der 2. Liga gegen den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing Management-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-26T08:15:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-16T12:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg\" \/>\n<meta name=\"author\" content=\"Patrick Bissig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patrick Bissig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/\"},\"author\":{\"name\":\"Patrick Bissig\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/6f62f5c8e10cbbafe84df0d9b0e8ba64\"},\"headline\":\"Sportvereine &#8211; Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?\",\"datePublished\":\"2015-03-26T08:15:32+00:00\",\"dateModified\":\"2015-06-16T12:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/\"},\"wordCount\":758,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2015\\\/03\\\/St.-Pauli.jpg\",\"keywords\":[\"Budget\",\"Dienstleistung\",\"Fanzufriedenheit\",\"FC Bayern\",\"FC St. Pauli\",\"NBA\",\"Newsletter\",\"Newsletter 1\\\/2015\",\"NFL\",\"Raiffeisen Super League\",\"Service-Profit-Chain\",\"Sportmarketing\"],\"articleSection\":{\"1\":\"Dienstleistung\",\"2\":\"Marketing Management\",\"3\":\"Sport Marketing\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/\",\"name\":\"Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit? - Marketing Management-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2015\\\/03\\\/St.-Pauli.jpg\",\"datePublished\":\"2015-03-26T08:15:32+00:00\",\"dateModified\":\"2015-06-16T12:00:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/6f62f5c8e10cbbafe84df0d9b0e8ba64\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2015\\\/03\\\/St.-Pauli.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2015\\\/03\\\/St.-Pauli.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportvereine &#8211; Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\",\"name\":\"Marketing Management-Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/6f62f5c8e10cbbafe84df0d9b0e8ba64\",\"name\":\"Patrick Bissig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g\",\"caption\":\"Patrick Bissig\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/author\\\/biss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit? - Marketing Management-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/","og_locale":"de_DE","og_type":"article","og_title":"Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?","og_description":"\u00abAlso wenn di\u00e4 eso spielet, isches ja keis Wunder, dass niemer meh gaht gu luege!\u00bb, ist eine viel geh\u00f6rte Aussage. Doch kommt es nur auf den sportlichen Erfolg an? Wenn ja, wie kann dann ein Verein wie der FC St. Pauli einen Zuschauerschnitt von 96% verzeichnen, obwohl der Klub in der 2. Liga gegen den [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/","og_site_name":"Marketing Management-Blog","article_published_time":"2015-03-26T08:15:32+00:00","article_modified_time":"2015-06-16T12:00:57+00:00","og_image":[{"url":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg","type":"","width":"","height":""}],"author":"Patrick Bissig","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Patrick Bissig","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/"},"author":{"name":"Patrick Bissig","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/6f62f5c8e10cbbafe84df0d9b0e8ba64"},"headline":"Sportvereine &#8211; Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?","datePublished":"2015-03-26T08:15:32+00:00","dateModified":"2015-06-16T12:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/"},"wordCount":758,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg","keywords":["Budget","Dienstleistung","Fanzufriedenheit","FC Bayern","FC St. Pauli","NBA","Newsletter","Newsletter 1\/2015","NFL","Raiffeisen Super League","Service-Profit-Chain","Sportmarketing"],"articleSection":{"1":"Dienstleistung","2":"Marketing Management","3":"Sport Marketing"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/","name":"Sportvereine - Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit? - Marketing Management-Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg","datePublished":"2015-03-26T08:15:32+00:00","dateModified":"2015-06-16T12:00:57+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/6f62f5c8e10cbbafe84df0d9b0e8ba64"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#primaryimage","url":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg","contentUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2015\/03\/St.-Pauli.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/sportvereine-sportlicher-erfolg-als-einziges-mittel-zur-steigerung-der-fanzufriedenheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/marketingmanagement\/"},{"@type":"ListItem","position":2,"name":"Sportvereine &#8211; Sportlicher Erfolg als einziges Mittel zur Steigerung der Fanzufriedenheit?"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/","name":"Marketing Management-Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/6f62f5c8e10cbbafe84df0d9b0e8ba64","name":"Patrick Bissig","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19a17958461c1332cabc23ed9622a268bd05c06d8af1e7bb77acbcda0b6de782?s=96&d=mm&r=g","caption":"Patrick Bissig"},"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/author\/biss\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/7570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/comments?post=7570"}],"version-history":[{"count":9,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/7570\/revisions"}],"predecessor-version":[{"id":7671,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/7570\/revisions\/7671"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/media?parent=7570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/categories?post=7570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/tags?post=7570"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/features?post=7570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}