{"id":6624,"date":"2014-09-03T11:09:19","date_gmt":"2014-09-03T09:09:19","guid":{"rendered":"http:\/\/blog.zhaw.ch\/marketingmanagement\/?p=6624"},"modified":"2014-09-02T10:06:11","modified_gmt":"2014-09-02T08:06:11","slug":"blogs-rund-um-die-zhaw-teil-1","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/","title":{"rendered":"Blogs rund um die ZHAW &#8211; Teil 1"},"content":{"rendered":"<p>Es wird kr\u00e4ftig gebloggt an der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften (ZHAW). Welches Thema interessiert Sie am meisten?<\/p>\n<p><strong>Angewandte Sprachen &#8211; Studium und Beruf<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg\" alt=\"Sprachen\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6649\" \/><\/a><\/p>\n<p>Dieser Blog gibt Einblicke in Studium, Weiterbildungen und m\u00f6gliche Berufsfelder des Bachelorstudiengangs Angewandte Sprachen. <a href=\"http:\/\/blog.zhaw.ch\/angewandte-sprachen\/\" title=\"Hier\" target=\"_blank\">Hier<\/a> der Link zum Blog. <\/p>\n<p><strong>BiCar-Zukunft der Mikromobilit\u00e4t in der Stadt<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/BICar-e1408623262810.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/BICar-e1408623262810.jpg\" alt=\"BICar\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6648\" \/><\/a><\/p>\n<p>Mit BiCar entwickelt die ZHAW School of Engineering ein innovatives urbanes Verkehrsangebot (System und dazugeh\u00f6riges Fahrzeug), dass fl\u00e4chensparsam und energieeffizient unsere Mobilit\u00e4t von morgen sichern k\u00f6nnte. Unter der Leitung des Zentrums f\u00fcr Produkt- und Prozessentwicklung (ZPP) arbeiten f\u00fcnf Institute der School of Engineering an diesem Vorhaben interdisziplin\u00e4r zusammen.  Der Blog gibt <a href=\"http:\/\/blog.zhaw.ch\/bicar\/\" title=\"hierzu\" target=\"_blank\">hierzu<\/a> einen \u00dcberblick.<\/p>\n<p><strong>Blog f\u00fcr Forschung und Entwicklung<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/copy-cropped-forschungssupport_header.png\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/copy-cropped-forschungssupport_header.png\" alt=\"copy-cropped-forschungssupport_header\" width=\"1000\" height=\"288\" class=\"alignleft size-full wp-image-6658\" \/><\/a><\/p>\n<p><a href=\"http:\/\/blog.zhaw.ch\/forschungssupport\/\" title=\"Hier\" target=\"_blank\">Hier<\/a> finden sich ganz unterschiedliche Beitr\u00e4ge zu den Themen Forschung und Entwicklung der ZHAW. <\/p>\n<p><strong>BWL\/Skills-Blog<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/cropped-bwl-e1408623606890.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/cropped-bwl-e1408623606890.jpg\" alt=\"cropped-bwl\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6659\" \/><\/a><\/p>\n<p>Worum es sich in den Beitr\u00e4gen des Blogs des Zentrums f\u00fcr innovative Didaktik (ZID) dreht, erfahren Sie <a href=\"http:\/\/blog.zhaw.ch\/bwlskills\/ueber-uns\/\" title=\"hier\" target=\"_blank\">hier<\/a>.<\/p>\n<p><strong>Data Science made in Switzerland<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/DataScience-e1408623297436.png\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/DataScience-e1408623297436.png\" alt=\"DataScience\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6646\" \/><\/a><\/p>\n<p>Alle Artikel rund um die Daten-Wissenschaft verfasst das DataLab der ZHAW <a href=\"http:\/\/blog.zhaw.ch\/datascience\/\" title=\"hier\" target=\"_blank\">hier<\/a> in Englisch.<\/p>\n<p><strong>Diversity@ZHAW<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/diversity-e1408623310752.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/diversity-e1408623310752.jpg\" alt=\"diversity\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6645\" \/><\/a><\/p>\n<p>Ein Meinungsaustausch zum Themenbereich Diversity. Lesen Sie <a href=\"http:\/\/blog.zhaw.ch\/diversity\/\" title=\"hier\" target=\"_blank\">hier<\/a>, was Mitarbeiter\/innen sowie Studenten\/innen besch\u00e4ftigt.<\/p>\n<p><strong>ICCLAB<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/icclab_logo-e1408623951558.png\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/icclab_logo-e1408623951558.png\" alt=\"icclab_logo\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6661\" \/><\/a><\/p>\n<p>Das ICCLab erweitert das Wissen im Bereich rund um Cloud Computing und berichtet <a href=\"http:\/\/blog.zhaw.ch\/icclab\/\" title=\"hier\" target=\"_blank\">hier<\/a> dar\u00fcber.<\/p>\n<p><strong>International Social Work Exchange Dayton &#8211; Zurich<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/cropped-Bild-e1408623278423.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/cropped-Bild-e1408623278423.jpg\" alt=\"cropped-Bild\" width=\"850\" height=\"244\" class=\"alignleft size-full wp-image-6647\" \/><\/a><\/p>\n<p><a href=\"http:\/\/blog.zhaw.ch\/socialworkexchange\/about-us\/\" title=\"Hier\" target=\"_blank\">Hier<\/a> teilen Studenten und Dozierende ihre Erfahrungen aus ihrem zweiw\u00f6chigen Austauschprogramm mit Ihnen. Der Austausch zwischen dem &#8222;Social Work Department&#8220; der Wright State University (WSU) in Dayton Ohio und das Departement f\u00fcr Soziale Arbeit der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften (ZHAW) findet j\u00e4hrlich in Z\u00fcrich oder in Dayton Ohio statt.<\/p>\n<p><strong>Mobine<\/strong><br \/>\n<a href=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Mobine-e1408623359155.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Mobine-e1408623359155.jpg\" alt=\"Mobine\" width=\"850\" height=\"245\" class=\"alignleft size-full wp-image-6644\" \/><\/a><\/p>\n<p>Neuigkeiten und Forschungsresultate aus dem Bereich Verkehr und nachhaltige Mobilit\u00e4t stehen bei <a href=\"http:\/\/blog.zhaw.ch\/mobine\/\" title=\"diesem Blog\" target=\"_blank\">diesem Blog <\/a>im Zentrum.<\/p>\n<p>N\u00e4chste Woche stellen wir Ihnen sieben weitere ZHAW Blogs vor. Viel Spass beim durchleuten der angewandten Wissenschaft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es wird kr\u00e4ftig gebloggt an der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften (ZHAW). Welches Thema interessiert Sie am meisten? Angewandte Sprachen &#8211; Studium und Beruf Dieser Blog gibt Einblicke in Studium, Weiterbildungen und m\u00f6gliche Berufsfelder des Bachelorstudiengangs Angewandte Sprachen. Hier der Link zum Blog. BiCar-Zukunft der Mikromobilit\u00e4t in der Stadt Mit BiCar entwickelt die ZHAW School [&hellip;]<\/p>\n","protected":false},"author":110,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"features":[],"class_list":["post-6624","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blogs rund um die ZHAW - Teil 1 - Marketing Management-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blogs rund um die ZHAW - Teil 1\" \/>\n<meta property=\"og:description\" content=\"Es wird kr\u00e4ftig gebloggt an der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften (ZHAW). Welches Thema interessiert Sie am meisten? Angewandte Sprachen &#8211; Studium und Beruf Dieser Blog gibt Einblicke in Studium, Weiterbildungen und m\u00f6gliche Berufsfelder des Bachelorstudiengangs Angewandte Sprachen. Hier der Link zum Blog. BiCar-Zukunft der Mikromobilit\u00e4t in der Stadt Mit BiCar entwickelt die ZHAW School [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing Management-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-03T09:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg\" \/>\n<meta name=\"author\" content=\"Liora Lilienfeld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liora Lilienfeld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/\"},\"author\":{\"name\":\"Liora Lilienfeld\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/933c25b0f5326b61e76fc3dd7f3aa040\"},\"headline\":\"Blogs rund um die ZHAW &#8211; Teil 1\",\"datePublished\":\"2014-09-03T09:09:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/\"},\"wordCount\":318,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2014\\\/08\\\/Sprachen-e1408623061265.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/\",\"name\":\"Blogs rund um die ZHAW - Teil 1 - Marketing Management-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2014\\\/08\\\/Sprachen-e1408623061265.jpg\",\"datePublished\":\"2014-09-03T09:09:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/933c25b0f5326b61e76fc3dd7f3aa040\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#primaryimage\",\"url\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2014\\\/08\\\/Sprachen-e1408623061265.jpg\",\"contentUrl\":\"http:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2014\\\/08\\\/Sprachen-e1408623061265.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/blogs-rund-um-die-zhaw-teil-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blogs rund um die ZHAW &#8211; Teil 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\",\"name\":\"Marketing Management-Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/933c25b0f5326b61e76fc3dd7f3aa040\",\"name\":\"Liora Lilienfeld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g\",\"caption\":\"Liora Lilienfeld\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/author\\\/lile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blogs rund um die ZHAW - Teil 1 - Marketing Management-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/","og_locale":"de_DE","og_type":"article","og_title":"Blogs rund um die ZHAW - Teil 1","og_description":"Es wird kr\u00e4ftig gebloggt an der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften (ZHAW). Welches Thema interessiert Sie am meisten? Angewandte Sprachen &#8211; Studium und Beruf Dieser Blog gibt Einblicke in Studium, Weiterbildungen und m\u00f6gliche Berufsfelder des Bachelorstudiengangs Angewandte Sprachen. Hier der Link zum Blog. BiCar-Zukunft der Mikromobilit\u00e4t in der Stadt Mit BiCar entwickelt die ZHAW School [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/","og_site_name":"Marketing Management-Blog","article_published_time":"2014-09-03T09:09:19+00:00","og_image":[{"url":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg","type":"","width":"","height":""}],"author":"Liora Lilienfeld","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Liora Lilienfeld","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/"},"author":{"name":"Liora Lilienfeld","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/933c25b0f5326b61e76fc3dd7f3aa040"},"headline":"Blogs rund um die ZHAW &#8211; Teil 1","datePublished":"2014-09-03T09:09:19+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/"},"wordCount":318,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/","name":"Blogs rund um die ZHAW - Teil 1 - Marketing Management-Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg","datePublished":"2014-09-03T09:09:19+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/933c25b0f5326b61e76fc3dd7f3aa040"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#primaryimage","url":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg","contentUrl":"http:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2014\/08\/Sprachen-e1408623061265.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/blogs-rund-um-die-zhaw-teil-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/marketingmanagement\/"},{"@type":"ListItem","position":2,"name":"Blogs rund um die ZHAW &#8211; Teil 1"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/","name":"Marketing Management-Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/933c25b0f5326b61e76fc3dd7f3aa040","name":"Liora Lilienfeld","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/60b74a9806c6156c45af91dcbbe8b2f8f61ef5ffa2598247b38f59c245a765d9?s=96&d=mm&r=g","caption":"Liora Lilienfeld"},"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/author\/lile\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/6624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/comments?post=6624"}],"version-history":[{"count":35,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/6624\/revisions"}],"predecessor-version":[{"id":6715,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/6624\/revisions\/6715"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/media?parent=6624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/categories?post=6624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/tags?post=6624"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/features?post=6624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}