{"id":5269,"date":"2013-09-25T09:10:12","date_gmt":"2013-09-25T07:10:12","guid":{"rendered":"http:\/\/ianus.zhaw.ch\/marketingmanagement\/?p=5269"},"modified":"2014-07-03T14:51:20","modified_gmt":"2014-07-03T12:51:20","slug":"armin-ledergerber-zum-going-public-von-twitter","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/","title":{"rendered":"Armin Ledergerber zum Going-Public von Twitter"},"content":{"rendered":"<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/armin-ledergerber\/\">Armin Ledergerber<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/going-public\/\">Going-Public<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/social-media\/\">Social Media<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/srf\/\">SRF<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/twitter\/\">Twitter<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>Schlagw\u00f6rter: Armin Ledergerber, Going-Public, Social Media, SRF, Twitter<\/p>\n","protected":false},"author":132,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[37,220,519,534,613],"features":[],"class_list":["post-5269","post","type-post","status-publish","format-standard","hentry","category-social-media-marketing","tag-armin-ledergerber","tag-going-public","tag-social-media","tag-srf","tag-twitter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Armin Ledergerber zum Going-Public von Twitter - Marketing Management-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Armin Ledergerber zum Going-Public von Twitter\" \/>\n<meta property=\"og:description\" content=\"Schlagw\u00f6rter: Armin Ledergerber, Going-Public, Social Media, SRF, Twitter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing Management-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-25T07:10:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-03T12:51:20+00:00\" \/>\n<meta name=\"author\" content=\"Patricia Gwerder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Gwerder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/\"},\"author\":{\"name\":\"Patricia Gwerder\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/11d705f947b58f8054dc5b3276ab8569\"},\"headline\":\"Armin Ledergerber zum Going-Public von Twitter\",\"datePublished\":\"2013-09-25T07:10:12+00:00\",\"dateModified\":\"2014-07-03T12:51:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/\"},\"wordCount\":6,\"commentCount\":0,\"keywords\":[\"Armin Ledergerber\",\"Going-Public\",\"Social Media\",\"SRF\",\"Twitter\"],\"articleSection\":[\"Social Media Marketing\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/\",\"name\":\"Armin Ledergerber zum Going-Public von Twitter - Marketing Management-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\"},\"datePublished\":\"2013-09-25T07:10:12+00:00\",\"dateModified\":\"2014-07-03T12:51:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/11d705f947b58f8054dc5b3276ab8569\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/armin-ledergerber-zum-going-public-von-twitter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Armin Ledergerber zum Going-Public von Twitter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\",\"name\":\"Marketing Management-Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/11d705f947b58f8054dc5b3276ab8569\",\"name\":\"Patricia Gwerder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g\",\"caption\":\"Patricia Gwerder\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/author\\\/gwed\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Armin Ledergerber zum Going-Public von Twitter - Marketing Management-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/","og_locale":"de_DE","og_type":"article","og_title":"Armin Ledergerber zum Going-Public von Twitter","og_description":"Schlagw\u00f6rter: Armin Ledergerber, Going-Public, Social Media, SRF, Twitter","og_url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/","og_site_name":"Marketing Management-Blog","article_published_time":"2013-09-25T07:10:12+00:00","article_modified_time":"2014-07-03T12:51:20+00:00","author":"Patricia Gwerder","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Patricia Gwerder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/"},"author":{"name":"Patricia Gwerder","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/11d705f947b58f8054dc5b3276ab8569"},"headline":"Armin Ledergerber zum Going-Public von Twitter","datePublished":"2013-09-25T07:10:12+00:00","dateModified":"2014-07-03T12:51:20+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/"},"wordCount":6,"commentCount":0,"keywords":["Armin Ledergerber","Going-Public","Social Media","SRF","Twitter"],"articleSection":["Social Media Marketing"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/","name":"Armin Ledergerber zum Going-Public von Twitter - Marketing Management-Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website"},"datePublished":"2013-09-25T07:10:12+00:00","dateModified":"2014-07-03T12:51:20+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/11d705f947b58f8054dc5b3276ab8569"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/armin-ledergerber-zum-going-public-von-twitter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/marketingmanagement\/"},{"@type":"ListItem","position":2,"name":"Armin Ledergerber zum Going-Public von Twitter"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/","name":"Marketing Management-Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/11d705f947b58f8054dc5b3276ab8569","name":"Patricia Gwerder","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/648a1d1caa7e12fb5474b01dda84797ef06a50b12c9963595b75e41e2177de4b?s=96&d=mm&r=g","caption":"Patricia Gwerder"},"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/author\/gwed\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/5269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/users\/132"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/comments?post=5269"}],"version-history":[{"count":4,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/5269\/revisions"}],"predecessor-version":[{"id":6449,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/5269\/revisions\/6449"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/media?parent=5269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/categories?post=5269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/tags?post=5269"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/features?post=5269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}