{"id":11114,"date":"2020-05-13T07:29:11","date_gmt":"2020-05-13T05:29:11","guid":{"rendered":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?p=11114"},"modified":"2020-05-13T07:29:12","modified_gmt":"2020-05-13T05:29:12","slug":"hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/","title":{"rendered":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Von Corinne W\u00fcthrich<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Vor rund dreissig Jahren hat sich Familie Meier den Wunsch vom Eigenheim erf\u00fcllt und damit die gr\u00f6sste Investition ihres Lebens get\u00e4tigt. Mittlerweile haben die Kinder das Nest verlassen. Trotzdem m\u00f6chten Elisabeth und Peter Meier auch nach der Pensionierung in ihrem geliebten Haus im Gr\u00fcnen wohnen bleiben. Doch ihre Bank hat sie darauf aufmerksam gemacht, dass sie mit dem tieferen Renteneinkommen die Tragbarkeitsrichtlinien nicht mehr einhalten und das Haus daher verkaufen m\u00fcssen. Muss sich das Ehepaar wirklich vom Eigenheim trennen? Die <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/\" target=\"_blank\">Ersparniskasse Schaffhausen<\/a> bietet hier eine L\u00f6sung.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/portrait\/ueber-uns\/geschaeftsleitung-2\/\" target=\"_blank\">Daniel Burlon<\/a>, Mitglied der Gesch\u00e4ftsleitung und Leiter des Bereichs Kredite und Finanzierungen bei der <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/\" target=\"_blank\">Ersparniskasse Schaffhausen,<\/a> kennt viele Geschichten, wie diejenige des Ehepaars Meier aus seinem Gesch\u00e4ftsalltag. In dieser Situation eine Verkaufsempfehlung auszusprechen, widersprach seinem Verst\u00e4ndnis einer partnerschaftlichen Zusammenarbeit. Dies hat ihn dazu bewogen, eine massgeschneiderte L\u00f6sung zu suchen: Die <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">Hypo60+.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Daniel_Burlon_\u00a9bbf.ch_-1024x731.jpg\" alt=\"\" class=\"wp-image-11115\" \/><figcaption>Daniel Burlon, Leiter des Bereichs Kredite und Finanzierungen bei der Ersparniskasse Schaffhausen \u00a9 bbf.ch \/ Ersparniskasse Schaffhausen AG<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/portrait\/ueber-uns\/geschaeftsleitung-2\/\" target=\"_blank\"><strong>Daniel Burlon<\/strong><\/a><strong>, bei Familie Meier ist die Tragbarkeit nicht mehr gegeben. Was ist die Tragbarkeit genau?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gem\u00e4ss der Tragbarkeitsregel d\u00fcrfen s\u00e4mtliche Kosten f\u00fcr den Unterhalt der Immobilie maximal ein Drittel des j\u00e4hrlichen Bruttoeinkommens betragen. Da sich der Hypothekar-Zinssatz im Laufe der Jahre ver\u00e4ndern kann, rechnet die Bank mit einem kalkulatorischen Zinssatz von 4.5 bis 5 Prozent. Im Fall der Familie Meier k\u00f6nnte dies vor der Pensionierung wie folgt aussehen: <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"153\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg\" alt=\"\" class=\"wp-image-11118\" srcset=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg 1024w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-300x45.jpg 300w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-768x114.jpg 768w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1536x229.jpg 1536w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-2048x305.jpg 2048w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-500x74.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Setzt man nun die Kosten ins Verh\u00e4ltnis zum j\u00e4hrlichen Bruttoeinkommen von CHF 120&#8217;000 erh\u00e4lt man die Tragbarkeit von 29 Prozent. Da dieser Wert unter 33 Prozent liegt, ist die Tragbarkeit gegeben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weshalb wird die Tragbarkeit nach der Pensionierung zum Problem?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch die Pensionierung verschlechtert sich die Einkommenssituation der meisten Personen in der Schweiz. Gem\u00e4ss der vom <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.bwo.admin.ch\/bwo\/de\/home.html\" target=\"_blank\">Bundesamt f\u00fcr Wohnungswesen<\/a> in Auftrag gegebenen und von der <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.zhaw.ch\/de\/hochschule\/\" target=\"_blank\">ZHAW<\/a> in Partnerschaft mit dem <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.hev-schweiz.ch\/\" target=\"_blank\">Hauseigent\u00fcmerverband Schweiz<\/a> im April 2019 erschienenen Studie <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.bwo.admin.ch\/bwo\/de\/home\/wie-wir-wohnen\/alter\/publikationen-bwo\/nachhaltige-sicherung-des-wohnraums-im-alter.html\" target=\"_blank\">\u00abNachhaltige Sicherung des Wohnraums im Alter\u00bb<\/a> verringerte sich das monatliche Einkommen von Paarhaushalten im Durchschnitt um 38 Prozent. Beziehen wir dies auf das Ehepaar Meier, so sinkt deren j\u00e4hrliches Einkommen auf CHF 74&#8217;400. Die Tragbarkeit liegt neu bei 47 Prozent und somit weit \u00fcber 33 Prozent. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie kann die <\/strong><a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\"><strong>Hypo60+<\/strong><\/a><strong> dem Ehepaar Meier helfen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Eigenheim der Familie Meier ist mit 50 Prozent belehnt. Mit der <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">Hypo60+<\/a> kann die Hypothek bis auf maximal 66 Prozent aufgestockt werden. Sie wird als Festhypothek abgeschlossen, wobei die Kunden die Laufzeit zwischen 5 und 10 Jahren frei w\u00e4hlen k\u00f6nnen. Bereits beim Abschluss ist also klar, welchen Betrag das Ehepaar f\u00fcr die Zinsen w\u00e4hrend der gesamten Laufzeit bezahlt. Dieser Betrag wird von der Aufstockung der Hypothek direkt auf ein gesperrtes und der Bank verpf\u00e4ndetes Konto eingezahlt. Das Haus bezahlt also seine Zinsen selbst. Und in der Kostenberechnung entf\u00e4llt der gr\u00f6sste Posten, denn die Hypothekarzinsen m\u00fcssen nicht mehr ber\u00fccksichtigt werden: <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"153\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-1024x153.jpg\" alt=\"\" class=\"wp-image-11121\" srcset=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-1024x153.jpg 1024w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-300x45.jpg 300w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-768x114.jpg 768w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-1536x229.jpg 1536w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-2048x305.jpg 2048w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-2-500x74.jpg 500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auch mit dem tieferen Einkommen von CHF 74&#8217;400 kann die Tragbarkeitsregel mit 13 Prozent eingehalten werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wird der gesamte Betrag der Hypothekarerh\u00f6hung auf das gesperrte Konto \u00fcberwiesen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falls die Kunden die Hypothek nur f\u00fcr die Begleichung der Hypothekarzinsen erh\u00f6hen, ja. Ansonsten stellen wir lediglich den Betrag f\u00fcr die effektiven Zinsen sicher. Bei Familie Meier betragen die Zinskosten f\u00fcr 10 Jahre CHF 100&#8217;000. Ihnen bleiben also CHF 60&#8217;000, die sie nach eigenem Gutd\u00fcnken ausgeben k\u00f6nnen, beispielsweise f\u00fcr die Renovation des Eigenheims, die laufenden Lebenskosten oder eine Reise. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-1024x683.jpg\" alt=\"\" class=\"wp-image-11122\" srcset=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-1024x683.jpg 1024w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-300x200.jpg 300w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-768x512.jpg 768w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-1536x1025.jpg 1536w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-2048x1367.jpg 2048w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/07_01_EKSH_MEMORY_MDL3758_K3_WEB_\u00a9bbf.ch_n-450x300.jpg 450w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>Dank Hypo60+ k\u00f6nnen Pensionierte weiterhin mit den Enkeln den eigenen Garten geniessen. \u00a9 bbf.ch \/ Ersparniskasse Schaffhausen AG<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Das klingt nach einem einmaligen Angebot. Wie gross ist das Interesse?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">Hypo60+<\/a> wurde 2017 lanciert und ist in der Region nach wie vor einmalig. Das Interesse ist seit der Einf\u00fchrung sehr gross. Insbesondere die Medienresonanz hat uns \u00fcberrascht. Die <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">Hypo60+<\/a> wurde sogar im <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/blog.tagesanzeiger.ch\/geldblog\/index.php\/70005\/die-angst-der-rentner-das-haus-zu-verlieren\/\" target=\"_blank\">Geldblog des Tages-Anzeigers<\/a> positiv erw\u00e4hnt. Infolge dieses Artikels wurden Auslandschweizer auf unser Angebot aufmerksam und kontaktierten uns. Dank der <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">Hypo60+<\/a> kann der dritte Lebensabschnitt ohne finanzielle Sorgen genossen werden. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-1024x427.jpg\" alt=\"\" class=\"wp-image-11125\" srcset=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-1024x427.jpg 1024w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-300x125.jpg 300w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-768x320.jpg 768w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-1536x640.jpg 1536w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot-500x208.jpg 500w, https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Screenshot.jpg 1879w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>Screenshot der Webseite \u00fcber die Hypo60+ der Ersparniskasse Schaffhausen<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr Informationen unter: <a rel=\"noreferrer noopener\" aria-label=\"https:\/\/www.ersparniskasse.ch\/hypo60\/ (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/hypo60\/\" target=\"_blank\">https:\/\/www.ersparniskasse.ch\/hypo60\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00dcber die Autorin<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium is-style-default\"><a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Corinne-W\u00fcthrich.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Corinne-W\u00fcthrich-300x225.jpg\" alt=\"\" class=\"wp-image-11128\" \/><\/a><figcaption>Fronwagplatz 4\n8200 Schaffhausen\n+41 52 624 80 92\nwww.bbf.ch<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Corinne W\u00fcthrich ist Assistentin der Gesch\u00e4ftsleitung bei der <a rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\" href=\"https:\/\/www.ersparniskasse.ch\/\" target=\"_blank\">Ersparniskasse Schaffhausen AG<\/a> und betreut dort den Bereich Marketing und Kommunikation. Neben der beruflichen T\u00e4tigkeit absolviert sie zurzeit bei der <a href=\"https:\/\/www.zhaw.ch\/de\/hochschule\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\">ZHAW<\/a> den <a href=\"https:\/\/www.zhaw.ch\/de\/sml\/weiterbildung\/detail\/kurs\/cas-marketing-corporate-communications\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (\u00f6ffnet in neuem Tab)\">CAS Marketing- &amp; Corporate Communications<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/alter\/\">Alter<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/amortisation\/\">Amortisation<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/budget\/\">Budget<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/bundesamt-fuer-wohnungswesen\/\">Bundesamt f\u00fcr Wohnungswesen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/cas-marketing-corporate-communications\/\">CAS Marketing- &amp; Corporate Communications<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/corinne-wuethrich\/\">Corinne W\u00fcthrich<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/daniel-burlon\/\">Daniel Burlon<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/dritter-lebensabschnitt\/\">dritter Lebensabschnitt<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/einkommen\/\">Einkommen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/ersparniskasse-schaffhausen\/\">Ersparniskasse Schaffhausen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/geldblog\/\">Geldblog<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/hauseigentuemerverband-schweiz\/\">Hauseigent\u00fcmerverband Schweiz<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/hypo60\/\">Hypo60+<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/hypothekarzinsen\/\">Hypothekarzinsen<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/imm\/\">IMM<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/institut-fur-marketing-management\/\">Institut f\u00fcr Marketing Management<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/liegenschaftswert\/\">Liegenschaftswert<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/nachhaltig\/\">nachhaltig<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/rentner\/\">Rentner<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/senioren\/\">Senioren<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/sicherung\/\">Sicherung<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/tages-anzeiger\/\">Tages-Anzeiger<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/tragbarkeitsregel\/\">Tragbarkeitsregel<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/umkehrhypothek\/\">Umkehrhypothek<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/wohnraum\/\">Wohnraum<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/zhaw\/\">zhaw<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/tag\/zhaw-school-of-management-and-law\/\">ZHAW School of Management and Law<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>Von Corinne W\u00fcthrich Vor rund dreissig Jahren hat sich Familie Meier den Wunsch vom Eigenheim erf\u00fcllt und damit die gr\u00f6sste Investition ihres Lebens get\u00e4tigt. Mittlerweile haben die Kinder das Nest verlassen. Trotzdem m\u00f6chten Elisabeth und Peter Meier auch nach der Pensionierung in ihrem geliebten Haus im Gr\u00fcnen wohnen bleiben. Doch ihre Bank hat sie darauf [&hellip;]<\/p>\n","protected":false},"author":312,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,3,13],"tags":[4266,4268,794,4267,742,4269,4270,4272,4271,4275,4274,4276,4278,4277,246,255,4273,2794,4279,501,4281,4282,4280,4283,4284,670,1629],"features":[],"class_list":["post-11114","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-branding-kommunikation","category-weiterbildung","tag-alter","tag-amortisation","tag-budget","tag-bundesamt-fuer-wohnungswesen","tag-cas-marketing-corporate-communications","tag-corinne-wuethrich","tag-daniel-burlon","tag-dritter-lebensabschnitt","tag-einkommen","tag-ersparniskasse-schaffhausen","tag-geldblog","tag-hauseigentuemerverband-schweiz","tag-hypo60","tag-hypothekarzinsen","tag-imm","tag-institut-fur-marketing-management","tag-liegenschaftswert","tag-nachhaltig","tag-rentner","tag-senioren","tag-sicherung","tag-tages-anzeiger","tag-tragbarkeitsregel","tag-umkehrhypothek","tag-wohnraum","tag-zhaw","tag-zhaw-school-of-management-and-law"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird - Marketing Management-Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird\" \/>\n<meta property=\"og:description\" content=\"Von Corinne W\u00fcthrich Vor rund dreissig Jahren hat sich Familie Meier den Wunsch vom Eigenheim erf\u00fcllt und damit die gr\u00f6sste Investition ihres Lebens get\u00e4tigt. Mittlerweile haben die Kinder das Nest verlassen. Trotzdem m\u00f6chten Elisabeth und Peter Meier auch nach der Pensionierung in ihrem geliebten Haus im Gr\u00fcnen wohnen bleiben. Doch ihre Bank hat sie darauf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/\" \/>\n<meta property=\"og:site_name\" content=\"Marketing Management-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-13T05:29:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-13T05:29:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg\" \/>\n<meta name=\"author\" content=\"suva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"suva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/\"},\"author\":{\"name\":\"suva\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\"},\"headline\":\"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird\",\"datePublished\":\"2020-05-13T05:29:11+00:00\",\"dateModified\":\"2020-05-13T05:29:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/\"},\"wordCount\":732,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2020\\\/05\\\/Berechnung-1-1024x153.jpg\",\"keywords\":[\"Alter\",\"Amortisation\",\"Budget\",\"Bundesamt f\u00fcr Wohnungswesen\",\"CAS Marketing- &amp; Corporate Communications\",\"Corinne W\u00fcthrich\",\"Daniel Burlon\",\"dritter Lebensabschnitt\",\"Einkommen\",\"Ersparniskasse Schaffhausen\",\"Geldblog\",\"Hauseigent\u00fcmerverband Schweiz\",\"Hypo60+\",\"Hypothekarzinsen\",\"IMM\",\"Institut f\u00fcr Marketing Management\",\"Liegenschaftswert\",\"nachhaltig\",\"Rentner\",\"Senioren\",\"Sicherung\",\"Tages-Anzeiger\",\"Tragbarkeitsregel\",\"Umkehrhypothek\",\"Wohnraum\",\"zhaw\",\"ZHAW School of Management and Law\"],\"articleSection\":{\"1\":\"Branding &amp; Kommunikation\",\"2\":\"Weiterbildung\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/\",\"name\":\"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird - Marketing Management-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2020\\\/05\\\/Berechnung-1-1024x153.jpg\",\"datePublished\":\"2020-05-13T05:29:11+00:00\",\"dateModified\":\"2020-05-13T05:29:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2020\\\/05\\\/Berechnung-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/files\\\/2020\\\/05\\\/Berechnung-1.jpg\",\"width\":2296,\"height\":342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/\",\"name\":\"Marketing Management-Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/#\\\/schema\\\/person\\\/8e3fd88b17ed80282ba7666e90fa5da3\",\"name\":\"suva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g\",\"caption\":\"suva\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/marketingmanagement\\\/author\\\/suva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird - Marketing Management-Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/","og_locale":"de_DE","og_type":"article","og_title":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird","og_description":"Von Corinne W\u00fcthrich Vor rund dreissig Jahren hat sich Familie Meier den Wunsch vom Eigenheim erf\u00fcllt und damit die gr\u00f6sste Investition ihres Lebens get\u00e4tigt. Mittlerweile haben die Kinder das Nest verlassen. Trotzdem m\u00f6chten Elisabeth und Peter Meier auch nach der Pensionierung in ihrem geliebten Haus im Gr\u00fcnen wohnen bleiben. Doch ihre Bank hat sie darauf [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/","og_site_name":"Marketing Management-Blog","article_published_time":"2020-05-13T05:29:11+00:00","article_modified_time":"2020-05-13T05:29:12+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg","type":"","width":"","height":""}],"author":"suva","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"suva","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/"},"author":{"name":"suva","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3"},"headline":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird","datePublished":"2020-05-13T05:29:11+00:00","dateModified":"2020-05-13T05:29:12+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/"},"wordCount":732,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg","keywords":["Alter","Amortisation","Budget","Bundesamt f\u00fcr Wohnungswesen","CAS Marketing- &amp; Corporate Communications","Corinne W\u00fcthrich","Daniel Burlon","dritter Lebensabschnitt","Einkommen","Ersparniskasse Schaffhausen","Geldblog","Hauseigent\u00fcmerverband Schweiz","Hypo60+","Hypothekarzinsen","IMM","Institut f\u00fcr Marketing Management","Liegenschaftswert","nachhaltig","Rentner","Senioren","Sicherung","Tages-Anzeiger","Tragbarkeitsregel","Umkehrhypothek","Wohnraum","zhaw","ZHAW School of Management and Law"],"articleSection":{"1":"Branding &amp; Kommunikation","2":"Weiterbildung"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/","name":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird - Marketing Management-Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1-1024x153.jpg","datePublished":"2020-05-13T05:29:11+00:00","dateModified":"2020-05-13T05:29:12+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/marketingmanagement\/files\/2020\/05\/Berechnung-1.jpg","width":2296,"height":342},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/hypo60-damit-das-eigenheim-im-alter-nicht-zur-hypothek-wird\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/marketingmanagement\/"},{"@type":"ListItem","position":2,"name":"Hypo60+ \u2013 Damit das Eigenheim im Alter nicht zur Hypothek wird"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#website","url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/","name":"Marketing Management-Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/marketingmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/marketingmanagement\/#\/schema\/person\/8e3fd88b17ed80282ba7666e90fa5da3","name":"suva","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40c8bd61df220eadf6e5481cf43dc7e86cda9707732035285b48521487832c5e?s=96&d=mm&r=g","caption":"suva"},"url":"https:\/\/blog.zhaw.ch\/marketingmanagement\/author\/suva\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/11114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/users\/312"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/comments?post=11114"}],"version-history":[{"count":9,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/11114\/revisions"}],"predecessor-version":[{"id":11151,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/posts\/11114\/revisions\/11151"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/media?parent=11114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/categories?post=11114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/tags?post=11114"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/marketingmanagement\/wp-json\/wp\/v2\/features?post=11114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}