{"id":592,"count":1,"description":"","link":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/","name":"GenAI Skills Hub","slug":"genai-skills-hub","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GenAI Skills Hub Archive - Lehren und Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GenAI Skills Hub Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/\" \/>\n<meta property=\"og:site_name\" content=\"Lehren und Lernen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/tag\\\/genai-skills-hub\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/tag\\\/genai-skills-hub\\\/\",\"name\":\"GenAI Skills Hub Archive - Lehren und Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/tag\\\/genai-skills-hub\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/tag\\\/genai-skills-hub\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GenAI Skills Hub\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/\",\"name\":\"Lehren und Lernen\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/lehren-und-lernen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GenAI Skills Hub Archive - Lehren und Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/","og_locale":"de_DE","og_type":"article","og_title":"GenAI Skills Hub Archive","og_url":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/","og_site_name":"Lehren und Lernen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/","url":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/","name":"GenAI Skills Hub Archive - Lehren und Lernen","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/#website"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/tag\/genai-skills-hub\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/"},{"@type":"ListItem","position":2,"name":"GenAI Skills Hub"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/#website","url":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/","name":"Lehren und Lernen","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/wp-json\/wp\/v2\/tags\/592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.zhaw.ch\/lehren-und-lernen\/wp-json\/wp\/v2\/posts?tags=592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}