{"id":6319,"date":"2024-06-17T13:40:54","date_gmt":"2024-06-17T11:40:54","guid":{"rendered":"https:\/\/blog.zhaw.ch\/iap\/?p=6319"},"modified":"2024-06-17T13:40:54","modified_gmt":"2024-06-17T11:40:54","slug":"holakratie-ein-erfolgsrezept-fuer-organisationen","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/","title":{"rendered":"Holakratie \u2013 ein Erfolgsrezept?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Wie \u00fcberstehen Organisationen herausfordernde Zeiten? Formen der Selbstorganisation wie Holakratie scheinen die L\u00f6sung zu sein. Doch was steckt dahinter?<\/em><\/strong> <strong><em>Welche Rolle hat F\u00fchrung in solch neuen Organisationsformen und inwiefern stehen Kultur, Struktur und Zusammenarbeit in Beziehung? Erhalten Sie in diesem Beitrag Antworten und anschauliche Impulse aus Forschung und Praxis.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Autorin:<\/em> Sonja St\u00f6ckli<br><em>Bild: <\/em>Adobe Stock<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In traditionellen Organisationsformen m\u00fcssen F\u00fchrungspersonen viele Entscheidungen treffen und kommen dadurch h\u00e4ufig an ihre Grenzen. Die bisherigen Kompetenzen und Routinen von Organisationen eignen sich nicht optimal, um rasch und kontextbezogen zu handeln. Das war in der Vergangenheit unproblematisch. Heute k\u00f6nnen neue Ans\u00e4tze der Zusammenarbeit f\u00fcr die aktuellen Herausforderungen unserer Zeit besser geeignet sein. Nebst der Beschleunigung kommt ein hohes Ausmass an Komplexit\u00e4t innerhalb und ausserhalb gr\u00f6sserer Organisationen hinzu: Politische Konflikte, globale Lieferketten, Klimaver\u00e4nderung, Energie- und Gesundheitskrisen, k\u00fcnstliche Intelligenz u.v.m. Einzelne Menschen k\u00f6nnen diese Menge an Komplexit\u00e4t nicht \u00fcberblicken und aussteuern. Trifft Beschleunigung auf Komplexit\u00e4t, entsteht eine unberechenbare, dynamische Umwelt, die eine Unmenge an offenen Fragen aufwirft und Entscheidungen erfordert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-in-traditionellen-strukturen-sind-mitarbeitende-oft-unzufrieden-holakratie-bietet-mehr-selbststeuerung\"><strong>In traditionellen Strukturen sind Mitarbeitende oft unzufrieden \u2013 Holakratie bietet mehr Selbststeuerung<\/strong><br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine breite Menge an wissenschaftlich fundierten Daten zeigt auf, dass Mitarbeitende in einer klassischen Unternehmensform h\u00e4ufig unzufrieden sind. Oft genannte Gr\u00fcnde aus einer Umfrage des Gallup Engagement Index aus dem Jahr 2020 in Deutschland sind: Unternehmenskultur, vorherrschender F\u00fchrungsstil sowie mangelnde Gestaltungsfreiheit. Diesen Aspekten kann Holakratie entgegenwirken.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em><strong>\u00abEs braucht mehr als eine Ver\u00e4nderung von Abl\u00e4ufen und Prozessen.\u00bb<\/strong><\/em><\/p>\n<cite>Antwort aus einem Forschungsinterview<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der grosse Unterschied zwischen traditionellen Organisationsstrukturen und Selbstorganisationen besteht darin, dass sich letztere darauf fokussiert, Mitarbeitenden und Teams mehr M\u00f6glichkeit zur Selbststeuerung einzur\u00e4umen. Daraus einhergehend wird Autorit\u00e4t dezentralisiert. Dazu z\u00e4hlen beispielsweise Fragen zur strategischen Ausrichtung einer Unternehmung oder wie anhand relevanter Kennzahlen der operative Fortschritt gepr\u00fcft werden kann. Die Ausf\u00fchrung der Arbeit und die F\u00fchrungsaspekte sind damit nicht l\u00e4nger getrennte, sondern verbundene Handlungen. Dort, wo Wissen vorhanden ist, finden Wertsch\u00f6pfung und F\u00fchrung statt. Daraus resultieren die Entscheidungsfindung und die kollektive Gestaltung der lokalen Aufbauorganisation.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em><strong>\u00abDie Bildung und Kultivierung selbstorganisierter Arbeitsweisen sind bei weitem keine Selbstl\u00e4ufer. Vielmehr erfordern die Einf\u00fchrung dieser Strukturen und Arbeitsprinzipien eine sorgf\u00e4ltige Planung und Begleitung. Es ist wichtig, dass die Mitarbeitenden die erforderlichen F\u00e4higkeiten und die richtige Unterst\u00fctzung haben, um erfolgreich in einer selbstorganisierten Umgebung arbeiten zu k\u00f6nnen. Dies betrifft weniger Formalismen, die kognitiv schnell erfasst und erlernt werden k\u00f6nnen, als vielmehr die Haltung und den Umgang untereinander, ergo die Kultur.\u00bb<\/strong><\/em><\/p>\n<cite><em>Dominik Grolimund, Jeanette Herzog, Andreas Hertel<\/em><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-was-braucht-es-fur-eine-erfolgreiche-umsetzung\"><strong>Was braucht es f\u00fcr eine erfolgreiche Umsetzung?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mindestens ebenso wichtig wie die Selbstorganisation als strukturelle Basis f\u00fcr die Zusammenarbeit sind die Menschen, die das Konzept energetisieren und zum Leben erwecken. Denn Holakratie ist keineswegs die Heilung f\u00fcr s\u00e4mtliche Probleme einer Organisation. Sie bietet der Organisation allerdings dynamikrobuste Ans\u00e4tze, um mit neu auftretenden Problemstellungen effektiver umzugehen. Es geht um einen direkten Umgang mit Komplexit\u00e4t und Dynamik, indem Verantwortlichkeiten und Entscheidungskompetenzen entlang definierter Rollen breiter verteilt werden. Dabei werden klassisch-hierarchische F\u00fchrungspersonen entlastet und Mitarbeitende erleben mehr Verantwortung und Gestaltungsspielraum. Holakratie ist eine Herausforderung, eine Weiterentwicklung, eine Chance, jedoch keine L\u00f6sung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In einer qualitativen Forschungsarbeit am Departement Angewandte Psychologie der Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften wurden die wesentlichen Faktoren f\u00fcr die \u00dcbertragung von Holakratie in die Praxis untersucht. Dabei wurden qualitative Interviews mit Beratenden im Bereich Holakratie \/ Selbstorganisation durchgef\u00fchrt und Erfolgsfaktoren erfragt. Die Ergebnisse sind in das Buch \u00abSelbstorganisation mit Holakratie\u2026eine Frage der Kultur!\u00bb eingeflossen (vgl. Box weiter unten).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Folgende Bausteine sind wichtig bei diesem Prozess:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Motivation<\/li>\n\n\n\n<li>F\u00fchrung<\/li>\n\n\n\n<li>Ressourcen: Wissen, Geduld, Zeit<\/li>\n\n\n\n<li>Geld<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn sich eine Organisation dazu entschliesst, eine Transformation zur Holakratie durchzuf\u00fchren, m\u00fcssen Fragen nach der <strong>Motivation<\/strong> und den Erwartungen unbedingt gekl\u00e4rt und im Anschluss in die Organisation kommuniziert werden. Es braucht mehr als die Ver\u00e4nderung von Abl\u00e4ufen und Prozessen. Mitarbeitende sollen sich intensiver mit dem eigenen Verst\u00e4ndnis von Sinnhaftigkeit, Macht sowie Kooperation auseinandersetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Rolle der (dann meist noch klassisch-hierarchischen)<strong> F\u00fchrung<\/strong> ist von gro\u00dfer Bedeutung. Die F\u00fchrung f\u00e4llt die Entscheidung zum Systemwechsel in Richtung Holakratie aus einer machtvollen Position heraus und vertritt damit den Ver\u00e4nderungsprozess gegen\u00fcber der Organisation. Diese Entscheidung soll klar und sichtbar nach aussen kommuniziert werden, beispielsweise an einer gemeinsamen Feier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ohne die n\u00f6tigen <strong>Ressourcen<\/strong>, allen voran<strong> Zeit, Geld und Wissen <\/strong>gelingt die Einf\u00fchrung und Etablierung von Holakratie in der Praxis nicht. Alle drei Elemente sind eng aneinandergekn\u00fcpft. Wissen \u00fcber Selbstorganisation, \u00fcber holakratische Rollen, Routinen und Praktiken muss breit in der Organisation verteilt sein und angewandt werden, um bestehende Wissens- und Kompetenzgef\u00e4lle zu \u00fcberwinden. Flie\u00dfen die Informationen zudem \u00fcber die \u00abalten\u00bb Informationswege der klassischen Organisation, werden diese hierarchischen Linien eher verst\u00e4rkt als aufgel\u00f6st.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein m\u00f6glicher Weg sind durchmischte Lerngruppen, die durchaus auch organisations\u00fcbergreifend sein k\u00f6nnen. Dabei werden unter anderem der Umgang mit Spannungen, Konflikt- und Feedbackkompetenzen oder Moderationskompetenzen (Facilitation) einge\u00fcbt. Zus\u00e4tzlich zu Lernr\u00e4umen braucht es Freir\u00e4ume, damit sich die Menschen in der neuen Situation orientieren k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-bedeutung-einer-erfahrenen-begleitung-und-positive-effekte\"><strong>Die Bedeutung einer erfahrenen Begleitung und positive Effekte<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Einf\u00fchrung der Holakratie ist ein strukturiertes Vorgehen essenziell. Einerseits wird diese Struktur durch das Konzept Holakratie zur Verf\u00fcgung gestellt, andererseits sollte sie durch eine erfahrene Person begleitet werden. Diese Beratungsperson erarbeitet eine Transformationsarchitektur, bietet Schulungen und Workshops an, definiert Rollen und Verantwortlichkeiten und gestaltet Meetings sowie Prozesse neu. Zudem werden die Kreisstrukturen etabliert und kontinuierliches Feedback und Anpassungen gef\u00f6rdert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Interne Organisationsentwicklung darf die Ans\u00e4tze der Holakratie uneingeschr\u00e4nkt nutzen. Beratungen dazu bieten wir auch beim IAP an. Eine offizielle Unterst\u00fctzung bei der Einf\u00fchrung von Holakratie bei externen Kund:innen darf hingegen nur durch zertifizierte Beratende erfolgen. So ergibt sich ein Gesch\u00e4ftsmodell aus Zertifizierungen und Beratung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Positive Effekte von selbstorganisiertem Arbeiten zeigen Aspekte wie wertsch\u00e4tzende Offenheit, Reflexionsf\u00e4higkeit, Zugewandtheit und Vertrauen. Diese Qualit\u00e4ten sind genau genommen bei jeglicher Zusammenarbeit n\u00fctzlich, beispielsweise auch in klassischen Organisationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kultiviert und gelebt werden kann eine Selbstorganisation mit Holakratie nur durch die Organisation selbst.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-weitere-informationen\"><strong>Weitere Informationen<\/strong>:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.zhaw.ch\/de\/psychologie\/ueber-uns\/medien-news\/blog-podcast\/#c236748\">IAP-Podcast \u00abHolakratie \u2013 eine Frage der Kultur?\u00bb<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-light-green-cyan-background-color has-background wp-block-paragraph\">Das Buch \u00abSelbstorganisation mit Holakratie\u2026eine Frage der Kultur!\u00bb vermittelt Spielregeln der Holakratie und zeigt die hohe Relevanz von kulturellen Aspekten auf. Leser:innen erhalten einen spannenden Einblick in das Ph\u00e4nomen der Selbstorganisation und welche Bausteine f\u00fcr eine erfolgreiche Umsetzung in der Praxis relevant sind. Das Buch kann beim <a href=\"https:\/\/link.springer.com\/book\/10.1007\/978-3-662-68777-2\">Springer Verlag<\/a> erworben werden.<br><br><strong>Zu den Autor:innen des Buches:<\/strong><br><br><strong>Dominik Grolimund<\/strong> ist Psychologe und Informatiker und arbeitet am Zentrum f\u00fcr Leadership, Coaching und Changemanagement als Berater (IAP\/ZHAW). In seiner Arbeit begleitet er Einzelpersonen, Teams und Organisationen in Ver\u00e4nderungsprozessen.<br><br><strong>Jeanette Herzog<\/strong> ist Arbeits- und Organisationspsychologin. Als systemische Organisations- und Teamentwicklerin legt sie ihren Fokus auf Kulturprozesse und Potentialentfaltung. Sie ist Gesch\u00e4ftsf\u00fchrerin der Unternehmensberatung Hejcon GmbH.<br><br><strong>Andreas Hertel<\/strong> ist freier Transformationsbegleiter und Coach. Schwerpunkte seiner Arbeit sind wirksame Kooperation und Selbstorganisation, F\u00fchrungs- und Strategieentwicklung sowie die potenzialfokussierte Entwicklung von Menschen, Teams und Organisationen.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:27%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-1024x1024.jpg\" alt=\"\" class=\"wp-image-6350\" srcset=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-1024x1024.jpg 1024w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-300x300.jpg 300w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-150x150.jpg 150w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-768x768.jpg 768w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-24x24.jpg 24w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-48x48.jpg 48w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb-96x96.jpg 96w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Pressebild_Sonja-Stoeckli_WEB_bearb.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:73%\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Sonja St\u00f6ckli<\/strong> absolvierte bis Ende Mai 2024 ein Praktikum am Institut f\u00fcr <br>Angewandte Psychologie IAP am Zentrum Leadership, Coaching, Beratung sowie Changemanagement. Sie ist freiberufliche Radiomoderatorin und studiert Wirtschaftspsychologie an der Hochschule Luzern.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie \u00fcberstehen Organisationen herausfordernde Zeiten? Formen der Selbstorganisation wie Holakratie scheinen die L\u00f6sung zu sein. Doch was steckt dahinter? Welche Rolle hat F\u00fchrung in solch neuen Organisationsformen und inwiefern stehen Kultur, Struktur und Zusammenarbeit in Beziehung? Erhalten Sie in diesem Beitrag Antworten und anschauliche Impulse aus Forschung und Praxis. Autorin: Sonja St\u00f6ckliBild: Adobe Stock In [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":6338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,55],"tags":[],"features":[],"class_list":["post-6319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-der-mensch-in-der-flexiblen-arbeitswelt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Holakratie \u2013 ein Erfolgsrezept? - Psychologie im Alltag nutzen<\/title>\n<meta name=\"description\" content=\"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Holakratie \u2013 ein Erfolgsrezept?\" \/>\n<meta property=\"og:description\" content=\"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/\" \/>\n<meta property=\"og:site_name\" content=\"Psychologie im Alltag nutzen\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T11:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\"},\"headline\":\"Holakratie \u2013 ein Erfolgsrezept?\",\"datePublished\":\"2024-06-17T11:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/\"},\"wordCount\":1226,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/06\\\/Blog-Selbstorganisation_WEB.jpg\",\"articleSection\":{\"1\":\"Der Mensch in der flexiblen Arbeitswelt\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/\",\"name\":\"Holakratie \u2013 ein Erfolgsrezept? - Psychologie im Alltag nutzen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/06\\\/Blog-Selbstorganisation_WEB.jpg\",\"datePublished\":\"2024-06-17T11:40:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\"},\"description\":\"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/06\\\/Blog-Selbstorganisation_WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/06\\\/Blog-Selbstorganisation_WEB.jpg\",\"width\":945,\"height\":630,\"caption\":\"Woman discussing her ideas with her team in a meeting. Business woman giving a presentation to a group of business people in an office.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/06\\\/17\\\/holakratie-ein-erfolgsrezept-fuer-organisationen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holakratie \u2013 ein Erfolgsrezept?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\",\"name\":\"Psychologie im Alltag nutzen\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/author\\\/bolj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Holakratie \u2013 ein Erfolgsrezept? - Psychologie im Alltag nutzen","description":"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/","og_locale":"de_DE","og_type":"article","og_title":"Holakratie \u2013 ein Erfolgsrezept?","og_description":"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.","og_url":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/","og_site_name":"Psychologie im Alltag nutzen","article_published_time":"2024-06-17T11:40:54+00:00","og_image":[{"width":945,"height":630,"url":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/"},"author":{"name":"Redaktion","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed"},"headline":"Holakratie \u2013 ein Erfolgsrezept?","datePublished":"2024-06-17T11:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/"},"wordCount":1226,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg","articleSection":{"1":"Der Mensch in der flexiblen Arbeitswelt"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/","url":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/","name":"Holakratie \u2013 ein Erfolgsrezept? - Psychologie im Alltag nutzen","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg","datePublished":"2024-06-17T11:40:54+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed"},"description":"IAP Blogbeitrag \u00fcber holakratisch gef\u00fchrte Unternehmen und deren Vorteile gegen\u00fcber Unternehmen mit traditionellem F\u00fchrungsstil.","breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/06\/Blog-Selbstorganisation_WEB.jpg","width":945,"height":630,"caption":"Woman discussing her ideas with her team in a meeting. Business woman giving a presentation to a group of business people in an office."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/06\/17\/holakratie-ein-erfolgsrezept-fuer-organisationen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/iap\/"},{"@type":"ListItem","position":2,"name":"Holakratie \u2013 ein Erfolgsrezept?"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/iap\/#website","url":"https:\/\/blog.zhaw.ch\/iap\/","name":"Psychologie im Alltag nutzen","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/iap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/blog.zhaw.ch\/iap\/author\/bolj\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/comments?post=6319"}],"version-history":[{"count":29,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6319\/revisions"}],"predecessor-version":[{"id":6361,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6319\/revisions\/6361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media\/6338"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media?parent=6319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/categories?post=6319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/tags?post=6319"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/features?post=6319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}