{"id":6265,"date":"2024-04-22T13:07:39","date_gmt":"2024-04-22T11:07:39","guid":{"rendered":"https:\/\/blog.zhaw.ch\/iap\/?p=6265"},"modified":"2024-04-22T13:07:40","modified_gmt":"2024-04-22T11:07:40","slug":"der-einsatz-von-diagnostik-in-der-psychologie","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/","title":{"rendered":"Der Einsatz von Diagnostik in der Psychologie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Psychologische Diagnostik ist ein wichtiger Eckpfeiler der Psychologie und eng mit deren historischen Entwicklung verbunden. Welche Formen von psychologischer Diagnostik haben sich im Laufe der Zeit entwickelt? Und wie wird sie in der Praxis sinnvoll eingesetzt?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Autor:<\/em> Simon C. Hardegger<br><em>Bild: <\/em>Adobe Stock<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die fr\u00fchen Wurzeln der Disziplin Psychologische Diagnostik reichen zur\u00fcck bis ins 19. Jahrhundert und zeigen deren grundlegende Bedeutung: Mit der Gr\u00fcndung eines psychotechnischen Labors 1879 durch Wilhelm Wundt in Leipzig wurden zugleich die Grundsteine f\u00fcr psychologische Diagnostik (damals noch Psychotechnik) und f\u00fcr Psychologie als eigenst\u00e4ndiges Fachgebiet gelegt. Sie steht h\u00e4ufig als Anfang oder Vorarbeit einer handlungsorientierten psychologischen Intervention.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\"><strong>\u00abPsychologische Diagnostik &#8211; Definition\u00bb<\/strong><br><br>Psychologische Diagnostik ist ein Teilgebiet der Psychologie und zugleich ein wichtiger Teil der Berufst\u00e4tigkeit von Psycholog:innen. Man geht davon aus, dass etwa ein Viertel aller psychologischen T\u00e4tigkeiten diagnostischer Natur ist.<br><br>Bei der&nbsp;psychologischen Diagnostik&nbsp;geht es darum, bestimmte Merkmale einer Person, Gruppe oder Organisation in einem strukturierten Prozess&nbsp;zu erfassen. Dies geschieht ausgehend von einer Frage- oder Problemstellung basierend auf wissenschaftlichen Methoden und Verfahren z. B. im Hinblick auf Motive, Interessen, Pers\u00f6nlichkeitseigenschaften, Werte, Leistungsfaktoren, Verhaltensaspekte, soziale Einflussfaktoren oder relevante Situationsvariablen. Dabei k\u00f6nnen Interviewleitf\u00e4den, Verhaltensbeobachtungen oder Testverfahren zur Anwendung kommen.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-entwicklung-und-fachbereiche\"><strong>Entwicklung und Fachbereiche<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die fr\u00fchen Entwicklungen der psychologischen Diagnostik waren im Geist der damaligen Zeit stark auf Testverfahren ausgerichtet und brachten bereits erste wichtige Prinzipien \u00fcber deren Anwendung hervor, die bis heute g\u00fcltig sind. Das IAP Institut f\u00fcr Angewandte Psychologie erkannte und systematisierte das entstandene Wissen seit Beginn seiner Existenz 1923 und erweiterte die als Psychodiagnostik genannte Anwendung bereits seit den 1960er-Jahren auf komplexere Praxisanwendungen wie z. B. &nbsp;die \u00abTalentf\u00f6rderung\u00bb. Die am IAP entwickelte Praxiskompetenz wurde seit 1937 dem interessierten Publikum zug\u00e4nglich gemacht, indem erstmals unabh\u00e4ngig von den Universit\u00e4ten eine Ausbildungsst\u00e4tte in Psychologie geschaffen wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aus den Anf\u00e4ngen von psychologischer Diagnostik hat sich mit der Zeit eine zunehmende Spezialisierung in verschiedene Teil-Fachbereiche mit ganz eigenen Anforderungen und Besonderheiten weiterentwickelt wie z. B. Verkehrspsychologie, Berufs-, Studien- und Laufbahnberatung oder Forensische Psychologie. Die Verkehrspsychologie und Berufseignungsdiagnostik datieren auf den Beginn des 20. Jahrhunderts und waren beide gepr\u00e4gt von sowohl zivilen als auch milit\u00e4rischen Anforderungen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\" id=\"block-3ad8a62a-10ac-4c65-9a49-db66671f3479\"><em style=\"font-weight: bold\"><em><strong>\u00abDas Ziel von psychologischer Diagnostik besteht darin, handlungsleitende Erkenntnisse f\u00fcr eine Entscheidung, eine Intervention oder eine Beratung zu gewinnen.\u00bb<\/strong><\/em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simon Carl Hardegger<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-einsatz-von-diagnostik-in-der-praxis\"><strong>Einsatz von Diagnostik in der Praxis<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/04\/Berufs-Studien-Laufbahnberatung_web.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"472\" src=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/04\/Berufs-Studien-Laufbahnberatung_web.jpg\" alt=\"\" class=\"wp-image-6308\" srcset=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/04\/Berufs-Studien-Laufbahnberatung_web.jpg 709w, https:\/\/blog.zhaw.ch\/iap\/files\/2024\/04\/Berufs-Studien-Laufbahnberatung_web-300x200.jpg 300w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><\/a><figcaption class=\"wp-element-caption\">Beratungssituation. Quelle: Webseite www.zhaw.ch <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Anwendungsfelder von Diagnostik in der Praxis sind vielf\u00e4ltig:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Klassische Eignungsdiagnostik<\/strong> im Rahmen von Rekrutierungs- oder Bef\u00f6rderungsprozessen: im Hinblick auf die Entscheidung, ob jemand eingestellt bzw. bef\u00f6rdert werden soll oder eben nicht oder f\u00fcr Aussagen \u00fcber die F\u00fchrungsf\u00e4higkeit von Personen.<\/li>\n\n\n\n<li><strong>Berufswahl- und Laufbahndiagnostik<\/strong>: in der Regel eingebettet in einen beraterischen Rahmen im Hinblick auf selbstgesteuerte Entwicklungsprozesse.<\/li>\n\n\n\n<li>Einsatz im Bereich <strong>Schulpsychologie<\/strong>: z. B. bei F\u00f6rdersettings wie Erg\u00e4nzungsunterricht oder Klassenwechsel sowie zur Begabtenf\u00f6rderung.<\/li>\n\n\n\n<li><strong>Verkehrspsychologische Diagnostik: <\/strong>Auswahl von Berufspersonal f\u00fcr T\u00e4tigkeiten wie Schienenfahrzeugf\u00fchrende, Busfahrer:innen, Schiffsf\u00fchrende, Pilot:innen, aber auch die Abkl\u00e4rung von leistungsschwachen oder straff\u00e4lligen Verkehrsteilnehmenden zum Schutz der Allgemeinheit.<\/li>\n\n\n\n<li><strong>Sicherheitspsychologische Diagnostik<\/strong>: Eignungsdiagnostik im Sicherheitskontext unter Anwendung einer Risikoperspektive: z. B. Arbeit in Sicherheits- und Rettungsorganisationen oder Kernkraftwerken.<\/li>\n\n\n\n<li><strong>Klinische Psychologie<\/strong>: z. B. Identifikation psychischer Beeintr\u00e4chtigungen und Leidensformen, um geeignete Massnahmen zu definieren sowie therapeutische Settings aufzusetzen.<\/li>\n\n\n\n<li><strong>Rechtspsychologie<\/strong>: z. B. zur Feststellung von Schuldf\u00e4higkeit oder R\u00fcckfallprognosen oder im Rahmen von aussagenpsychologischen Gutachten.<\/li>\n<\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-der-mensch-als-risiko\"><strong>Der Mensch als Risiko<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine noch junge Form von psychologischer Diagnostik besteht in der Beurteilung von menschlichen Risikofaktoren im Berufskontext. Dabei steht die Betrachtung des Menschen als Tr\u00e4ger:in von Risikofaktoren mit potenziellen Sch\u00e4digungskonsequenzen im Vordergrund. Solche <strong>Arten menschlicher Risikofaktoren<\/strong> sind z. B.:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inkompetenz im Sinne von Nicht-Wissen oder Nicht-K\u00f6nnen<\/li>\n\n\n\n<li>Selbstsch\u00e4digung z. B. durch Missbrauch von Alkohol, Drogen oder Medikamenten<\/li>\n\n\n\n<li>Menschliches Fehlverhalten im Zuge von z. B. Ablenkung, Ged\u00e4chtnisl\u00fccken, Fehleinsch\u00e4tzungen etc.<\/li>\n\n\n\n<li>Lasche Arbeitseinstellung z. B. mit der Tendenz zu minimalistischem Verhalten<\/li>\n\n\n\n<li>\u00dcbertretungen von Regeln entgegen klaren Anweisungen<\/li>\n\n\n\n<li>Vors\u00e4tzliche Regelbr\u00fcche z. B. in Form von Betrug, Informationsmissbrauch, Mobbing, Sachbesch\u00e4digung, Diebstahl, sexuelle Bel\u00e4stigung etc.<\/li>\n\n\n\n<li>Destruktives F\u00fchrungsverhalten, sei es als Folge von Inkompetenz oder einer egoistisch-ausbeuterischen Grundhaltung<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Psychologische Risikodiagnostik verfolgt schliesslich folgende<strong> Ziele<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e4ventives Schaffen von g\u00fcnstigen Voraussetzungen im Hinblick auf Sicherheit im Sinne eines sicheren Systemzustands<\/li>\n\n\n\n<li>Vermeiden von Sach-, finanziellen, physischen oder psychischen Sch\u00e4den<\/li>\n\n\n\n<li>Schutz der Vorteile und Werte einer Organisation und der Menschen darin bzw. auch der mit der Organisation nach aussen in Interaktion stehenden Menschen und Organisationen oder der Umwelt.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-risikodiagnostik-in-der-praxis-ein-fallbeispiel\"><strong>Risikodiagnostik in der Praxis \u2013 ein Fallbeispiel<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Betrachten wir ein kurzes Fallbeispiel: Eine national t\u00e4tige Organisation f\u00fchrte eine gross angelegte Risikoanalyse durch. Dabei ist sie darauf gestossen, dass f\u00fcr bestimmte Funktionen Integrit\u00e4tsrisiken bestehen, die im Extremfall katastrophale Konsequenzen haben k\u00f6nnen. Aus diesem Grund wollte die Organisation solche Integrit\u00e4tsrisiken bei Neueinstellungen systematisch untersuchen lassen. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Untersuchung durch das IAP wurde ein trimodales Setting angelegt:<\/p>\n\n\n\n<ol class=\"wp-block-list\" style=\"list-style-type:1\">\n<li>Ein psychologisches Testverfahren im Umfang von 75 Minuten<\/li>\n\n\n\n<li>Ein 2.5 Stunden dauerndes, strukturiertes Interview mit Ausrichtung auf Risikoaspekte wie <br>z. B. Pers\u00f6nlichkeit, Normen, Antriebsdynamik, Beeinflussbarkeit, Motive Werte, Biografie, Lebensstil und Destruktivit\u00e4t<\/li>\n\n\n\n<li>Eine Rollensimulation zur \u00dcberpr\u00fcfung der Beeinflussbarkeit<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Die Auswertung erfolgte durch den folgenden Prozess: Identifikation von Auff\u00e4lligkeiten \u2013 Bilden von Risiko-Clustern \u2013 Bewerten der Risiken und Empfehlungen zur Risikokontrolle. Die Untersuchung wurde durch zwei spezialisierte Psycholog:innen durchgef\u00fchrt und in einem Auswertungsbericht ausf\u00fchrlich dokumentiert. Als Abschluss der Analyse wurden die Resultate mit der auftraggebenden Organisation besprochen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weitere Informationen:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einen vollst\u00e4ndigen Text zum Thema (inkl. aller Quellenangaben) finden Sie im Beitrag \u00abPsychologische Diagnostik \u2013 ein wichtiger Eckpfeiler in der Psychologie\u00bb im 4. Kapitel des Buchs \u00abWas bewirkt Psychologie in Arbeit und Gesellschaft?\u00bb (Hrsg. Christoph Negri und Maja Goedertier). Das Buch ist im Mai 2023 anl\u00e4sslich des 100-Jahr-Jubil\u00e4ums des IAP im Springer-Verlag erschienen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Kapitel-4-Psychologische-Diagnostik.pdf\">Laden Sie das Kapitel 4 aus dem Buch hier herunter.<\/a> <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-bottom is-image-fill\" style=\"grid-template-columns:27% auto\"><figure class=\"wp-block-media-text__media\" style=\"background-image:url(https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard.jpg);background-position:50% 50%\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard.jpg\" alt=\"\" class=\"wp-image-5862 size-full\" srcset=\"https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard.jpg 300w, https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard-150x150.jpg 150w, https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard-24x24.jpg 24w, https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard-48x48.jpg 48w, https:\/\/blog.zhaw.ch\/iap\/files\/2022\/04\/hard-96x96.jpg 96w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\" style=\"font-size:14px\"><strong><a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/hard\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simon Carl Hardegger<\/a><\/strong> ist ausgebildeter Psychologe und arbeitet als Dozent und Berater am IAP Institut f\u00fcr Angewandte Psychologie. Er leitet das Zentrum Diagnostik, Verkehrs- &amp; Sicherheitspsychologie. <\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Psychologische Diagnostik ist ein wichtiger Eckpfeiler der Psychologie und eng mit deren historischen Entwicklung verbunden. Welche Formen von psychologischer Diagnostik haben sich im Laufe der Zeit entwickelt? Und wie wird sie in der Praxis sinnvoll eingesetzt? Autor: Simon C. HardeggerBild: Adobe Stock Die fr\u00fchen Wurzeln der Disziplin Psychologische Diagnostik reichen zur\u00fcck bis ins 19. Jahrhundert [&hellip;]<\/p>\n","protected":false},"author":223,"featured_media":6269,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,168],"tags":[],"features":[],"class_list":["post-6265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-assessment-sicherheit-verkehr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Der Einsatz von Diagnostik in der Psychologie - IAP Blog<\/title>\n<meta name=\"description\" content=\"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Einsatz von Diagnostik in der Psychologie\" \/>\n<meta property=\"og:description\" content=\"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/\" \/>\n<meta property=\"og:site_name\" content=\"Psychologie im Alltag nutzen\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T11:07:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T11:07:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\"},\"headline\":\"Der Einsatz von Diagnostik in der Psychologie\",\"datePublished\":\"2024-04-22T11:07:39+00:00\",\"dateModified\":\"2024-04-22T11:07:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/\"},\"wordCount\":1013,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/03\\\/Blog-psych-Diagnostik_web.jpg\",\"articleSection\":{\"1\":\"Assessment - Sicherheit - Verkehr\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/\",\"name\":\"Der Einsatz von Diagnostik in der Psychologie - IAP Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/03\\\/Blog-psych-Diagnostik_web.jpg\",\"datePublished\":\"2024-04-22T11:07:39+00:00\",\"dateModified\":\"2024-04-22T11:07:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\"},\"description\":\"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/03\\\/Blog-psych-Diagnostik_web.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2024\\\/03\\\/Blog-psych-Diagnostik_web.jpg\",\"width\":945,\"height\":631,\"caption\":\"Bild: Adobe Stock\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2024\\\/04\\\/22\\\/der-einsatz-von-diagnostik-in-der-psychologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Einsatz von Diagnostik in der Psychologie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\",\"name\":\"Psychologie im Alltag nutzen\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/4d4e456db800b0dcc51526c3417f57ed\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/author\\\/bolj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der Einsatz von Diagnostik in der Psychologie - IAP Blog","description":"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/","og_locale":"de_DE","og_type":"article","og_title":"Der Einsatz von Diagnostik in der Psychologie","og_description":"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.","og_url":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/","og_site_name":"Psychologie im Alltag nutzen","article_published_time":"2024-04-22T11:07:39+00:00","article_modified_time":"2024-04-22T11:07:40+00:00","og_image":[{"width":945,"height":631,"url":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/"},"author":{"name":"Redaktion","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed"},"headline":"Der Einsatz von Diagnostik in der Psychologie","datePublished":"2024-04-22T11:07:39+00:00","dateModified":"2024-04-22T11:07:40+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/"},"wordCount":1013,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg","articleSection":{"1":"Assessment - Sicherheit - Verkehr"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/","url":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/","name":"Der Einsatz von Diagnostik in der Psychologie - IAP Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg","datePublished":"2024-04-22T11:07:39+00:00","dateModified":"2024-04-22T11:07:40+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed"},"description":"Die psychologische Diagnostik: geschichtliche Entwicklung, Formen und ihr sinnvoller Einsatz in der Praxis. Erfahre mehr im Blogbeitrag.","breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2024\/03\/Blog-psych-Diagnostik_web.jpg","width":945,"height":631,"caption":"Bild: Adobe Stock"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/iap\/2024\/04\/22\/der-einsatz-von-diagnostik-in-der-psychologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/iap\/"},{"@type":"ListItem","position":2,"name":"Der Einsatz von Diagnostik in der Psychologie"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/iap\/#website","url":"https:\/\/blog.zhaw.ch\/iap\/","name":"Psychologie im Alltag nutzen","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/iap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/4d4e456db800b0dcc51526c3417f57ed","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/730160e5d0d4170155b5a6075757d2fcd5698658545111a9484b11e2822ca161?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/blog.zhaw.ch\/iap\/author\/bolj\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/users\/223"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/comments?post=6265"}],"version-history":[{"count":31,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6265\/revisions"}],"predecessor-version":[{"id":6310,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/6265\/revisions\/6310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media\/6269"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media?parent=6265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/categories?post=6265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/tags?post=6265"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/features?post=6265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}