{"id":5303,"date":"2021-10-08T14:04:23","date_gmt":"2021-10-08T12:04:23","guid":{"rendered":"https:\/\/blog.zhaw.ch\/iap\/?p=5303"},"modified":"2022-04-12T21:36:55","modified_gmt":"2022-04-12T19:36:55","slug":"talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/","title":{"rendered":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>K\u00f6nnen einige von uns besser Menschen f\u00fchren als andere? Wenn das so ist, welches Potenzial braucht jemand, um eine erfolgreiche F\u00fchrungskraft zu werden? Die zentrale Frage f\u00fcr Unternehmen ist, wie sich das Talent zum F\u00fchren bei Mitarbeitenden einfach finden und erfolgreich nutzen l\u00e4sst.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Text: Maja Goedertier<\/em><br><em>Bild: Brooke Cagle<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Arbeitswelt stellen F\u00fchrungskr\u00e4fte einen massgeblichen Erfolgsfaktor f\u00fcr die Zukunft einer Unternehmung dar. Sie sollen Mitarbeitende darin unterst\u00fctzen, sich rasch auf ver\u00e4ndernde Situationen einzustellen und mit komplexen Situationen und Informationen umzugehen. Unternehmen wollen in komplexen Gegebenheiten mit qualifizierten Mitarbeitenden vorangehen, welche die anstehenden Herausforderungen bew\u00e4ltigen k\u00f6nnen. Personen mit Talent zum F\u00fchren, sind schlummernde Ressourcen einer Organisation, welche f\u00fcr das Gelingen von Projekten und das Erreichen der Unternehmensziele erfolgsbestimmend sind. Diese Ressourcen gilt es zu finden, zu halten und zu entwickeln. Daneben ist f\u00fcr die Erfahrung der Mitarbeitenden innerhalb der Organisation (employee experience) sowie deren Identifikation mit dem Unternehmen zentral, dass sie gef\u00f6rdert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nach welchen Personen soll Ausschau gehalten werden?<\/strong><br>In der Regel suchen Organisationen im Rahmen von F\u00fchrungskr\u00e4fte-Nachwuchsprogrammen ambitionierte und motivierte Mitarbeitende mit Potenzial f\u00fcr Entwicklung auch innerhalb der Organisation. Diese sollen die Voraussetzung mitbringen, den bestehenden Firmenwerten und der gegebenen Leistungskultur zu entsprechen. Doch sind diese Mitarbeitenden per se auch optimale F\u00fchrungskr\u00e4fte?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Intelligenz, Gewissenhaftigkeit, Offenheit, emotionale Intelligenz, Lernagilit\u00e4t, Selbstvertrauen oder auch Selbstwirksamkeits\u00fcberzeugung sind wichtige Eigenschaften.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Empirische Belege zum Thema F\u00fchrungspotenzial zeigen konkrete Faktoren auf, die sich weitgehend mit dem bestehenden Expertenwissen decken. Zum einen werden Pers\u00f6nlichkeitseigenschaften wie zum Beispiel das intellektuelle Leistungspotenzial, Gewissenhaftigkeit, Offenheit, emotionale Intelligenz, Lernagilit\u00e4t, Selbstvertrauen oder auch Selbstwirksamkeits\u00fcberzeugung genannt, welche zu diesem Potenzial geh\u00f6ren. Daneben werden Verhaltensweisen wie Kommunikationsverm\u00f6gen, Entscheidungs- und Probleml\u00f6sef\u00e4higkeit, Selbstf\u00fchrungsf\u00e4higkeit, sowie soziale Kompetenz und Stress-Management genannt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig geh\u00f6ren zu den relevanten Kriterien auch die Motivation, Einfluss auf andere zu nehmen, die Einsatzbereitschaft f\u00fcr das Unternehmen sowie das generelle Wissen zum Thema F\u00fchrung. In den Studien wird ein breites Spektrum an Aspekten offenbar, welches dem F\u00fchrungspotenzial von Personen Rechnung tr\u00e4gt. Je nach Kontext k\u00f6nnen einzelne unternehmensspezifische Aspekte wichtiger sein als andere. Indem bei einem Talent Screening Schwerpunkte gelegt werden, besteht die M\u00f6glichkeit gezielt auf die zuk\u00fcnftige Firmen- und F\u00fchrungskultur einzuwirken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Digitalisierung erm\u00f6glicht eine einfachere Erkennung von internem F\u00fchrungspotenzial<\/strong><br>Nicht nur im prim\u00e4ren Bereich der Wertsch\u00f6pfungskette von Unternehmen hat in vergangener Zeit die Digitalisierung Einzug genommen. Sie hat sich inzwischen ebenso in den unterst\u00fctzenden Bereichen von Unternehmen etabliert. Befeuert durch die Pandemie hat die Auswahl von F\u00fchrungspersonen einen dynamischen Wandel absolviert und die Angebote von Online- und\/oder Pr\u00e4senzabkl\u00e4rungen sind vielf\u00e4ltig geworden. Durch die Erfahrung mit der Digitalisierung in der Personalselektion wurde nicht nur die Effizienz, sondern ebenso die Qualit\u00e4t derselben verbessert. Damit f\u00e4llt ihr je l\u00e4nger je mehr eine unternehmensstrategische Rolle zu, die es zu ber\u00fccksichtigen gilt. Einzelassessments, welche teilweise oder voll online durchgef\u00fchrt werden, stehen heute in einem anderen Licht da. Die Erfahrung hat gezeigt, dass auch unter dem Distanzgebot eine qualitativ hochstehende Abkl\u00e4rung m\u00f6glich ist. Entscheidend dabei ist, dass auf die Ausgangslage der Personen R\u00fccksicht genommen wird: im Fokus der Untersuchung m\u00fcssen nicht die F\u00fchrungskompetenzen selbst stehen \u2013 da es die noch zu entwickeln gilt \u2013 sondern die Voraussetzungen dazu.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Niederschwellige Informations- und Zugangswege sind wichtig f\u00fcr die Entwicklung von Mitarbeitenden.<\/em><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr ein Unternehmen ist es heutzutage wichtig, niederschwellige Informations- und Zugangswege f\u00fcr die Entwicklung von Mitarbeitenden zu erm\u00f6glichen. Durch Online-Abkl\u00e4rungen kann eine geringe Dauer bis zur Besetzung einer neuen oder bisherigen F\u00fchrungsstelle geschaffen werden. Auf diese Weise werden Entwicklungsm\u00f6glichkeiten f\u00fcr Interessierte absehbar gemacht. Daneben werden durch fundierte Verfahren die Auswahlentscheidungen objektiviert, weil alle Mitarbeitenden ein transparentes Programm f\u00fcr die pers\u00f6nliche Entwicklung durchlaufen k\u00f6nnen. Interessierte Talente nach unternehmensspezifischen Faktoren auszuw\u00e4hlen, wird insbesondere dann wichtig, wenn unternehmensweite Kompetenzl\u00fccken zur Planung interner und \/ oder externer Weiterbildungsangebote zu identifizieren sind. Eine einfache und wirkungsvolle Selektion von internen F\u00fchrungstalenten erh\u00f6ht somit nicht nur die Mitarbeiterbindung und -zufriedenheit, sondern tr\u00e4gt ebenso massgeblich zum zuk\u00fcnftigen Unternehmenserfolg bei.<\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-bottom\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px.jpg\" alt=\"\" class=\"wp-image-3440 size-full\" srcset=\"https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px.jpg 300w, https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px-150x150.jpg 150w, https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px-24x24.jpg 24w, https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px-48x48.jpg 48w, https:\/\/blog.zhaw.ch\/iap\/files\/2018\/12\/MajaGoedertier_9345_300x300px-96x96.jpg 96w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-small-font-size wp-block-paragraph\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/godm\/\" target=\"_blank\">Maja Goedertier<\/a><\/strong>, ist Psychologin und Beraterin im Bereich der Managementdiagnostik und Sicherheitspsychologie. Ihr Arbeitsschwerpunkt am IAP Institut f\u00fcr Angewandte Psychologie ist die psychologische Eignungsdiagnostik von F\u00fchrungspersonen sowie Personen in verschiedenen beruflichen Kontexten.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:63px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#45bfe3\"><strong>Leadership Talent Screen<\/strong> <strong>am IAP<\/strong><br>Nutzen Sie die vorhandenen Ressourcen ihrer Organisation und gewinnen Sie aus den eigenen Mitarbeitenden die zuk\u00fcnftigen F\u00fchrungskr\u00e4fte. Mehr erfahren Sie <a rel=\"noreferrer noopener\" href=\"https:\/\/www.zhaw.ch\/de\/psychologie\/dienstleistung\/personal-managementdiagnostik\/management-diagnostik\/leadership-talent-screen\/\" target=\"_blank\"><strong>hier<\/strong><\/a>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio lyte-align aligncenter\"><div class=\"lyte-wrapper\" title=\"IAP Leadership Talent Screen &ndash; F&uuml;hrungspotenzial schnell &amp;amp; sicher erkennen\" style=\"width:640px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_zrQB76sZRA8\"><div id=\"lyte_zrQB76sZRA8\" data-src=\"https:\/\/blog.zhaw.ch\/iap\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FzrQB76sZRA8%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\">IAP Leadership Talent Screen \u2013 F\u00fchrungspotenzial schnell &amp; sicher erkennen<\/div><\/div><button tabindex=\"0\" class=\"play\"><\/button><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/zrQB76sZRA8\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.zhaw.ch\/iap\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FzrQB76sZRA8%2F0.jpg\" alt=\"IAP Leadership Talent Screen &ndash; F&uuml;hrungspotenzial schnell &amp;amp; sicher erkennen\" width=\"640\" height=\"340\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:640px;margin:5px;\"><br\/><span class=\"lyte_disclaimer\">Defaulttext aus wp-youtube-lyte.php<\/span><\/div><figcaption><\/figcaption><\/figure>\n\n\n<div style=\"height:34px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Mehr zum Thema:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-psychologie-im-alltag-nutzen wp-block-embed-psychologie-im-alltag-nutzen\"><div class=\"wp-block-embed__wrapper\">\n<blockquote hcb-fetch-image-from=\"https:\/\/blog.zhaw.ch\/iap\/2021\/04\/01\/strukturelles-enttaeuschungsmanagement-eine-ungeliebte-aber-zentrale-fuehrungsaufgabe\/\" class=\"wp-embedded-content\" data-secret=\"hXSpvKq08Z\"><a href=\"https:\/\/blog.zhaw.ch\/iap\/2021\/04\/01\/strukturelles-enttaeuschungsmanagement-eine-ungeliebte-aber-zentrale-fuehrungsaufgabe\/\">Strukturelles Entt\u00e4uschungsmanagement \u2013 eine ungeliebte (aber zentrale) F\u00fchrungsaufgabe<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Strukturelles Entt\u00e4uschungsmanagement \u2013 eine ungeliebte (aber zentrale) F\u00fchrungsaufgabe&#8220; &#8212; Psychologie im Alltag nutzen\" src=\"https:\/\/blog.zhaw.ch\/iap\/2021\/04\/01\/strukturelles-enttaeuschungsmanagement-eine-ungeliebte-aber-zentrale-fuehrungsaufgabe\/embed\/#?secret=zpW5mQbTr3#?secret=hXSpvKq08Z\" data-secret=\"hXSpvKq08Z\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-psychologie-im-alltag-nutzen wp-block-embed-psychologie-im-alltag-nutzen\"><div class=\"wp-block-embed__wrapper\">\n<blockquote hcb-fetch-image-from=\"https:\/\/blog.zhaw.ch\/iap\/2020\/09\/09\/die-fuehrungsentwicklung-der-zukunft-ein-beispiel\/\" class=\"wp-embedded-content\" data-secret=\"bxCYbA6U0e\"><a href=\"https:\/\/blog.zhaw.ch\/iap\/2020\/09\/09\/die-fuehrungsentwicklung-der-zukunft-ein-beispiel\/\">Die F\u00fchrungsentwicklung der Zukunft. Ein Beispiel.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Die F\u00fchrungsentwicklung der Zukunft. Ein Beispiel.&#8220; &#8212; Psychologie im Alltag nutzen\" src=\"https:\/\/blog.zhaw.ch\/iap\/2020\/09\/09\/die-fuehrungsentwicklung-der-zukunft-ein-beispiel\/embed\/#?secret=N86dLha19Q#?secret=bxCYbA6U0e\" data-secret=\"bxCYbA6U0e\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"https:\/\/blog.zhaw.ch\/iap\/tag\/assessment\/\">assessment<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/iap\/tag\/fuehrung\/\">F\u00fchrung<\/a>, <a href=\"https:\/\/blog.zhaw.ch\/iap\/tag\/fuehrungsentwicklung\/\">F\u00fchrungsentwicklung<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>K\u00f6nnen einige von uns besser Menschen f\u00fchren als andere? Wenn das so ist, welches Potenzial braucht jemand, um eine erfolgreiche F\u00fchrungskraft zu werden? Die zentrale Frage f\u00fcr Unternehmen ist, wie sich das Talent zum F\u00fchren bei Mitarbeitenden einfach finden und erfolgreich nutzen l\u00e4sst. Text: Maja GoedertierBild: Brooke Cagle In der Arbeitswelt stellen F\u00fchrungskr\u00e4fte einen massgeblichen [&hellip;]<\/p>\n","protected":false},"author":532,"featured_media":5587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,65],"tags":[169,122,138],"features":[],"class_list":["post-5303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-fuehrungsentwicklung","tag-assessment","tag-fuehrung","tag-fuehrungsentwicklung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew - Psychologie im Alltag nutzen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew\" \/>\n<meta property=\"og:description\" content=\"K\u00f6nnen einige von uns besser Menschen f\u00fchren als andere? Wenn das so ist, welches Potenzial braucht jemand, um eine erfolgreiche F\u00fchrungskraft zu werden? Die zentrale Frage f\u00fcr Unternehmen ist, wie sich das Talent zum F\u00fchren bei Mitarbeitenden einfach finden und erfolgreich nutzen l\u00e4sst. Text: Maja GoedertierBild: Brooke Cagle In der Arbeitswelt stellen F\u00fchrungskr\u00e4fte einen massgeblichen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/\" \/>\n<meta property=\"og:site_name\" content=\"Psychologie im Alltag nutzen\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-08T12:04:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T19:36:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/c8886f16dac0dae183fd08581f4bd263\"},\"headline\":\"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew\",\"datePublished\":\"2021-10-08T12:04:23+00:00\",\"dateModified\":\"2022-04-12T19:36:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/\"},\"wordCount\":803,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2021\\\/10\\\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg\",\"keywords\":[\"assessment\",\"F\u00fchrung\",\"F\u00fchrungsentwicklung\"],\"articleSection\":{\"1\":\"F\u00fchrungsentwicklung\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/\",\"name\":\"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew - Psychologie im Alltag nutzen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2021\\\/10\\\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg\",\"datePublished\":\"2021-10-08T12:04:23+00:00\",\"dateModified\":\"2022-04-12T19:36:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/c8886f16dac0dae183fd08581f4bd263\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2021\\\/10\\\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/files\\\/2021\\\/10\\\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/2021\\\/10\\\/08\\\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/\",\"name\":\"Psychologie im Alltag nutzen\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/#\\\/schema\\\/person\\\/c8886f16dac0dae183fd08581f4bd263\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/iap\\\/author\\\/fina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew - Psychologie im Alltag nutzen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/","og_locale":"de_DE","og_type":"article","og_title":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew","og_description":"K\u00f6nnen einige von uns besser Menschen f\u00fchren als andere? Wenn das so ist, welches Potenzial braucht jemand, um eine erfolgreiche F\u00fchrungskraft zu werden? Die zentrale Frage f\u00fcr Unternehmen ist, wie sich das Talent zum F\u00fchren bei Mitarbeitenden einfach finden und erfolgreich nutzen l\u00e4sst. Text: Maja GoedertierBild: Brooke Cagle In der Arbeitswelt stellen F\u00fchrungskr\u00e4fte einen massgeblichen [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/","og_site_name":"Psychologie im Alltag nutzen","article_published_time":"2021-10-08T12:04:23+00:00","article_modified_time":"2022-04-12T19:36:55+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/"},"author":{"name":"Redaktion","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/c8886f16dac0dae183fd08581f4bd263"},"headline":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew","datePublished":"2021-10-08T12:04:23+00:00","dateModified":"2022-04-12T19:36:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/"},"wordCount":803,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg","keywords":["assessment","F\u00fchrung","F\u00fchrungsentwicklung"],"articleSection":{"1":"F\u00fchrungsentwicklung"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/","url":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/","name":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew - Psychologie im Alltag nutzen","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg","datePublished":"2021-10-08T12:04:23+00:00","dateModified":"2022-04-12T19:36:55+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/c8886f16dac0dae183fd08581f4bd263"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/iap\/files\/2021\/10\/brooke-cagle-uHVRvDr7pg-unsplash-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/iap\/2021\/10\/08\/talent-screening-als-chance-fuer-eine-erfolgreiche-fuehrungscrew\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/iap\/"},{"@type":"ListItem","position":2,"name":"Talent Screening als Chance f\u00fcr eine erfolgreiche F\u00fchrungscrew"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/iap\/#website","url":"https:\/\/blog.zhaw.ch\/iap\/","name":"Psychologie im Alltag nutzen","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/iap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/iap\/#\/schema\/person\/c8886f16dac0dae183fd08581f4bd263","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3612f9a05bafa95d62e2f0a7ac8705636b578b75dfc849c74bab90e05281e1a3?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/blog.zhaw.ch\/iap\/author\/fina\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/5303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/users\/532"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/comments?post=5303"}],"version-history":[{"count":17,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/5303\/revisions"}],"predecessor-version":[{"id":5847,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/posts\/5303\/revisions\/5847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media\/5587"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/media?parent=5303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/categories?post=5303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/tags?post=5303"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/iap\/wp-json\/wp\/v2\/features?post=5303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}