{"id":803,"count":1,"description":"","link":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/","name":"\u00dcbergewicht","slug":"uebergewicht","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00dcbergewicht Archive - Gesundheits\u00f6konomie @ ZHAW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcbergewicht Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Gesundheits\u00f6konomie @ ZHAW\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/\",\"url\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/\",\"name\":\"\u00dcbergewicht Archive - Gesundheits\u00f6konomie @ ZHAW\",\"isPartOf\":{\"@id\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcbergewicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website\",\"url\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/\",\"name\":\"Gesundheits\u00f6konomie @ ZHAW\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00dcbergewicht Archive - Gesundheits\u00f6konomie @ ZHAW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcbergewicht Archive","og_url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/","og_site_name":"Gesundheits\u00f6konomie @ ZHAW","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/","url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/","name":"\u00dcbergewicht Archive - Gesundheits\u00f6konomie @ ZHAW","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/uebergewicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/"},{"@type":"ListItem","position":2,"name":"\u00dcbergewicht"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website","url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/","name":"Gesundheits\u00f6konomie @ ZHAW","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/tags\/803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/posts?tags=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}