{"id":3768,"date":"2024-03-28T09:16:29","date_gmt":"2024-03-28T08:16:29","guid":{"rendered":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/?p=3768"},"modified":"2024-03-28T11:46:23","modified_gmt":"2024-03-28T10:46:23","slug":"lernen-sie-noch-oder-spielen-sie-schon","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/","title":{"rendered":"Lernen Sie noch oder spielen Sie schon?"},"content":{"rendered":"<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg\" alt=\"\" class=\"wp-image-3769\" style=\"aspect-ratio:1.499267935578331;width:702px;height:auto\" srcset=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg 1024w, https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-300x200.jpg 300w, https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-768x512.jpg 768w, https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1.jpg 1261w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><em>Bild: <\/em><a href=\"https:\/\/stock.adobe.com\/ch_de\/search?filters%5Bcontent_type%3Aphoto%5D=1&amp;filters%5Bcontent_type%3Aillustration%5D=1&amp;filters%5Bcontent_type%3Azip_vector%5D=1&amp;filters%5Bcontent_type%3Avideo%5D=1&amp;filters%5Bcontent_type%3Atemplate%5D=1&amp;filters%5Bcontent_type%3A3d%5D=1&amp;filters%5Bfetch_excluded_assets%5D=1&amp;filters%5Binclude_stock_enterprise%5D=1&amp;filters%5Bcontent_type%3Aimage%5D=1&amp;k=lego&amp;order=relevance&amp;safe_search=1&amp;limit=100&amp;search_page=1&amp;search_type=usertyped&amp;acp=&amp;aco=lego&amp;get_facets=0&amp;asset_id=416685004\"><strong><em>igradesign<\/em><\/strong><\/a><em>@ Adobe Stock<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von <a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/mick\/\" target=\"_blank\" rel=\"noreferrer noopener\">Katharina Demmel<\/a> und <a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/ange\/\">Prof. Dr. Alfr<\/a><a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/ange\/\" target=\"_blank\" rel=\"noreferrer noopener\">e<\/a><a href=\"https:\/\/www.zhaw.ch\/de\/ueber-uns\/person\/ange\/\">d Angerer<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abWohnst du noch oder lebst du schon?\u00bb. Der Werbe-Slogan von IKEA ist vielen ein Begriff. In adaptierter Form l\u00e4sst sich die Frage auch auf den Bildungskontext anwenden: \u00abLernen Sie noch oder spielen Sie schon?\u00bb Denn: spielbasiertes Lernen und Simulationsspiele gewinnen in der modernen Bildungswelt zunehmend an Bedeutung. Warum? Spielbasiertes Lernen ist nicht nur eine unterhaltsame Alternative und Abwechslung zum klassischen Frontalunterricht, sondern bietet auch nachweislich einen Nutzen f\u00fcr Lernende, und zwar jeden Alters. Oder in den Worten von Kerres et al. (2009): \u00abSpielen ist ganz essentiell mit Lernprozessen verbunden.\u00bb (S. 1).<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Das Beispiel Simulationsspiele f\u00fcr realit\u00e4tsnahe Erfahrungen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Untersuchungen haben gezeigt, dass Erfahrungsgenerierung durch Simulationsspiele einen hohen Einfluss auf das konzeptionelle Verst\u00e4ndnis eines Themas haben. Auch im Gesundheitswesen ist schon seit l\u00e4ngerem ein Einzug spielbasierter Lernmethoden, z. B. in Form von Simulationsspielen, zu beobachten. Simulationsspiele erm\u00f6glichen es, Wirkungszusammenh\u00e4nge komplexer Systeme (z. B. ein Spital) in gesch\u00fctzter Umgebung zu erleben. Fallstudien mit Pflegestudierenden in England haben gezeigt, dass Spiele mit Lego-Steinen (sog. LEGO\u00ae SERIOUS Play\u00ae) Engagement, Dialogbereitschaft und kritisches Denken f\u00f6rdern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der Nutzen spielbasierten Lernens im Kontext Gesundheitswesen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hier sind einige Gr\u00fcnde zusammengefasst, worin nun genau der Nutzen des spielbasierten Lernens als effektive Didaktik-Methode liegen kann.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Spielen f\u00f6rdert Motivation und Engagement:<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Gamifizierung, d. h. die Integration von Spielelementen und Mechanismen in einem bestimmten Kontext, k\u00f6nnen die Motivation steigern, sich mit den Lerninhalten auseinanderzusetzen und kanalisieren die Aufmerksamkeit auf das Spielthema (vgl. u.a. Rojas et al., 2016). Simulationsspiele (haptisch wie digital) erm\u00f6glichen es einerseits, mit einem Thema ganz praktisch und ggf. auch plastisch in Ber\u00fchrung zu kommen und gleichzeitig Optimierungsideen direkt zu testen und zu validieren.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Spielen f\u00f6rdert das kritische Denken:<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Spiele erfordern unsere volle Aufmerksamkeit, fordern uns heraus, L\u00f6sungen f\u00fcr Aufgaben zu finden und Entscheidungen zu treffen sowie Herausforderungen zu bew\u00e4ltigen. Dies sind alles Aktivit\u00e4ten und Aspekte, mit denen wir uns auch im Berufsalltag auseinandersetzen m\u00fcssen. Wenn Sie an die Welt der Spiele denken, stellen Sie sich z. B. Schach, Escape-Room-Spiele, Scrabble oder Kreuzwortr\u00e4tsel vor. Untersuchungen mit Doktorierenden im Bereich Healthcare Leadership sowie in der Ausbildung von Pflegefachpersonen zeigen, dass spielbasiertes Lernen ein effektiver Ansatz sein kann, um kritisches Denken und Probleml\u00f6sungsf\u00e4higkeiten zu f\u00f6rdern.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Spielen f\u00f6rdert Teamarbeit:<\/em><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Spielarten und -formen erfordern Zusammenarbeit. Vielleicht haben Sie schon einmal in der Gruppe nur mit ein paar Spaghetti, Klebeband und Marshmallow ausgestattet das Spiel \u00abwir bauen einen Turm\u00bb gespielt? Auch ein Blick in die Welt der Wissenschaft unterst\u00fctzt die These, dass spielbasiertes Lernen Teamwork-F\u00e4higkeiten erweitert. Gerade wenn es darum geht, Lerninhalte wie das Denken in Prozessen \u00fcber Fachbereichsgrenzen hinaus zu f\u00f6rdern, sind spielbasierte Lernformate hilfreich. Sie bieten den Lernenden einerseits die M\u00f6glichkeit, Lerninhalte gemeinsam zu erarbeiten und andererseits auch die M\u00f6glichkeit, diese Lerninhalte in Relation zueinander zu erleben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fazit: Spielen, um zu lernen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMenschen h\u00f6ren nicht auf zu spielen, weil sie alt werden, sie werden alt, weil sie aufh\u00f6ren zu spielen.\u00bb Dieses Zitat stammt von Oliver Wendel Holmes (1809-1894), einem US-amerikanischen Arzt und Schriftsteller. Wenn Sie also das n\u00e4chste Mal zu einem Spieleabend verknurrt werden, denken Sie daran: Spielen, sei es als Freizeitaktivit\u00e4t oder in einer Aus- oder Weiterbildung, hat positive Aspekte f\u00fcr unterschiedliche Kompetenzen und F\u00e4higkeiten, die wir im Alltag gebrauchen k\u00f6nnen. Und: Es h\u00e4lt uns jung!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falls Sie zum Thema spielbasiertes Lernen im digitalen Zeitalter noch mehr wissen wollen, besuchen Sie die Website zu unserem <a href=\"https:\/\/future.hospital\/die-projekte\/saeule-d-management-of-hospital-systems-mhs\/d1-intelligentes-fuehren-von-vernetzten-spitaelern\" target=\"_blank\" rel=\"noreferrer noopener\">SHIFT-Grossprojekt (Smart Hospital: Integrated Framework, Tools and Solutions) das Projekt D.1<\/a>, welches ein innovatives digitales Spitalmanagement-Simulationsspiel entwickelt. Falls Sie das Spiel selbst erleben wollen, am 29.05.2024 im Rahmen eines Events der Initiative <a href=\"https:\/\/www.zhaw.ch\/de\/fokusthemen\/zhaw-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">ZHAW digital<\/a>, haben Sie die M\u00f6glichkeit dazu.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"799\" src=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild2.jpg\" alt=\"\" class=\"wp-image-3770\" style=\"aspect-ratio:0.7509386733416771;width:395px;height:auto\" srcset=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild2.jpg 600w, https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild2-225x300.jpg 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\"><em>Entwicklung des Simulationsspiels im Rahmen des D.1-Projektes. Bildquelle: WIG ZHAW<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Katharina Demmel <\/strong>ist wissenschaftliche Mitarbeiterin der Fachstelle Management im Gesundheitswesen am WIG.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Prof. Dr. Alfred Angerer<\/strong> ist Leiter der Fachstelle Management im Gesundheitswesen am WIG.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Literaturhinweise<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ausbildung -Weiterbildung.ch. (2021). Praxis-Ratgeber f\u00fcr Bildungsinstitute. Lernspiele in der Erwachsenenbildung. Abgerufen von https:\/\/www.ausbildung-weiterbildung.ch\/Arbeitgeber\/Ratgeber?group=Erwachsenenbildung<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bauman, E. B. (2013). <em>Game-Based Teaching and Simulation in Nursing and Healthcare<\/em>. New York, NY: Springer Publishing Company.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Franco, P. F., &amp; DeLuca, D. A. (2019). Learning Through Action: Creating and Implementing a Strategy Game to Foster Innovative Thinking in Higher Education. <em>Simulation &amp; Gaming, 50(<\/em>1), 23\u201343. https:\/\/doi.org\/10.1177\/1046878118820892<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kerres, M., Bormann, M., &amp; Vervenne, M. (2009). Didaktische Konzeption von Serious Games: Zur Verkn\u00fcpfung von Spiel- und Lernangeboten. <em>MedienP\u00e4dagogik: Zeitschrift f\u00fcr Theorie und Praxis der Medienbildung, 2009<\/em>(Occasional Papers), 1\u201316. https:\/\/doi.org\/10.21240\/mpaed\/00\/2009.08.25.X<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Papakonstantinou, D., Poulymenopoulou, M., Malamateniou, F., &amp; Vassilacopoulos, G. (2011). A cloud-based semantic wiki for user training in healthcare process management. <em>Studies in Health Technology and Informatics, 169<\/em>, 93\u201397.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ranchhod, A., Gur\u0103u, C., Loukis, E., &amp; Trivedi, R. (2014). Evaluating the educational effectiveness of simulation games: A value generation model. <em>Information Sciences,<\/em> <em>264<\/em>, 75\u201390. https:\/\/doi.org\/10.1016\/j.ins.2013.09.008<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rojas, D., Kapralos, B., &amp; Dubrowski, A. (2016). The Role of Game Elements in Online Learning within Health Professions Education. <em>Studies in health technology and informatics, 220<\/em>, 329-34 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stead, R., Dimitrova, R., Pourgoura, A., Roberts, S., &amp; West, S. (2020). Building Knowledge and Learning Communities Using LEGO\u00ae in Nursing. In K. Gravett, N. Yakovchuk, &amp; I. M. Kinchin (Hrsg.), Enhancing Student-Centred Teaching in Higher Education (S. 77\u201396). Springer International Publishing. https:\/\/doi.org\/10.1007\/978-3-030-35396-4_6<\/p>\n<div class=\"pt-sm\">Schlagw\u00f6rter: <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/alfred-angerer\/\">Alfred Angerer<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/ausbildung\/\">Ausbildung<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/didaktik\/\">Didaktik<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/gesundheitswesen\/\">Gesundheitswesen<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/katharina-demmel\/\">Katharina Demmel<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/shift\/\">SHIFT<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/simulationsspiel\/\">Simulationsspiel<\/a>, <a href=\"http:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/tag\/weiterbildung\/\">Weiterbildung<\/a><br><\/div>","protected":false},"excerpt":{"rendered":"<p>Bild: igradesign@ Adobe Stock Von Katharina Demmel und Prof. Dr. Alfred Angerer \u00abWohnst du noch oder lebst du schon?\u00bb. Der Werbe-Slogan von IKEA ist vielen ein Begriff. In adaptierter Form l\u00e4sst sich die Frage auch auf den Bildungskontext anwenden: \u00abLernen Sie noch oder spielen Sie schon?\u00bb Denn: spielbasiertes Lernen und Simulationsspiele gewinnen in der modernen [&hellip;]<\/p>\n","protected":false},"author":394,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[6],"tags":[32,529,531,223,528,284,530,75],"features":[],"class_list":["post-3768","post","type-post","status-publish","format-standard","hentry","category-managementimgesundheitswesen","tag-alfred-angerer","tag-ausbildung","tag-didaktik","tag-gesundheitswesen","tag-katharina-demmel","tag-shift","tag-simulationsspiel","tag-weiterbildung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lernen Sie noch oder spielen Sie schon? - Gesundheits\u00f6konomie @ ZHAW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lernen Sie noch oder spielen Sie schon?\" \/>\n<meta property=\"og:description\" content=\"Bild: igradesign@ Adobe Stock Von Katharina Demmel und Prof. Dr. Alfred Angerer \u00abWohnst du noch oder lebst du schon?\u00bb. Der Werbe-Slogan von IKEA ist vielen ein Begriff. In adaptierter Form l\u00e4sst sich die Frage auch auf den Bildungskontext anwenden: \u00abLernen Sie noch oder spielen Sie schon?\u00bb Denn: spielbasiertes Lernen und Simulationsspiele gewinnen in der modernen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/\" \/>\n<meta property=\"og:site_name\" content=\"Gesundheits\u00f6konomie @ ZHAW\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T08:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-28T10:46:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"Gesundheits\u00f6konomie @ ZHAW\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gesundheits\u00f6konomie @ ZHAW\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/\"},\"author\":{\"name\":\"Gesundheits\u00f6konomie @ ZHAW\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/#\\\/schema\\\/person\\\/9f23ca3c7e8761fd1498ca155fa97be5\"},\"headline\":\"Lernen Sie noch oder spielen Sie schon?\",\"datePublished\":\"2024-03-28T08:16:29+00:00\",\"dateModified\":\"2024-03-28T10:46:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/\"},\"wordCount\":907,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/files\\\/2024\\\/03\\\/20240328_MiG_Bild1-1024x683.jpg\",\"keywords\":[\"Alfred Angerer\",\"Ausbildung\",\"Didaktik\",\"Gesundheitswesen\",\"Katharina Demmel\",\"SHIFT\",\"Simulationsspiel\",\"Weiterbildung\"],\"articleSection\":[\"Management im Gesundheitswesen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/\",\"name\":\"Lernen Sie noch oder spielen Sie schon? - Gesundheits\u00f6konomie @ ZHAW\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/files\\\/2024\\\/03\\\/20240328_MiG_Bild1-1024x683.jpg\",\"datePublished\":\"2024-03-28T08:16:29+00:00\",\"dateModified\":\"2024-03-28T10:46:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/#\\\/schema\\\/person\\\/9f23ca3c7e8761fd1498ca155fa97be5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/files\\\/2024\\\/03\\\/20240328_MiG_Bild1.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/files\\\/2024\\\/03\\\/20240328_MiG_Bild1.jpg\",\"width\":1261,\"height\":841},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/2024\\\/03\\\/28\\\/lernen-sie-noch-oder-spielen-sie-schon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lernen Sie noch oder spielen Sie schon?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/\",\"name\":\"Gesundheits\u00f6konomie @ ZHAW\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/#\\\/schema\\\/person\\\/9f23ca3c7e8761fd1498ca155fa97be5\",\"name\":\"Gesundheits\u00f6konomie @ ZHAW\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g\",\"caption\":\"Gesundheits\u00f6konomie @ ZHAW\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/gesundheitsoekonomie\\\/author\\\/grbd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lernen Sie noch oder spielen Sie schon? - Gesundheits\u00f6konomie @ ZHAW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/","og_locale":"de_DE","og_type":"article","og_title":"Lernen Sie noch oder spielen Sie schon?","og_description":"Bild: igradesign@ Adobe Stock Von Katharina Demmel und Prof. Dr. Alfred Angerer \u00abWohnst du noch oder lebst du schon?\u00bb. Der Werbe-Slogan von IKEA ist vielen ein Begriff. In adaptierter Form l\u00e4sst sich die Frage auch auf den Bildungskontext anwenden: \u00abLernen Sie noch oder spielen Sie schon?\u00bb Denn: spielbasiertes Lernen und Simulationsspiele gewinnen in der modernen [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/","og_site_name":"Gesundheits\u00f6konomie @ ZHAW","article_published_time":"2024-03-28T08:16:29+00:00","article_modified_time":"2024-03-28T10:46:23+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg","type":"","width":"","height":""}],"author":"Gesundheits\u00f6konomie @ ZHAW","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gesundheits\u00f6konomie @ ZHAW","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/"},"author":{"name":"Gesundheits\u00f6konomie @ ZHAW","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#\/schema\/person\/9f23ca3c7e8761fd1498ca155fa97be5"},"headline":"Lernen Sie noch oder spielen Sie schon?","datePublished":"2024-03-28T08:16:29+00:00","dateModified":"2024-03-28T10:46:23+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/"},"wordCount":907,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg","keywords":["Alfred Angerer","Ausbildung","Didaktik","Gesundheitswesen","Katharina Demmel","SHIFT","Simulationsspiel","Weiterbildung"],"articleSection":["Management im Gesundheitswesen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/","url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/","name":"Lernen Sie noch oder spielen Sie schon? - Gesundheits\u00f6konomie @ ZHAW","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1-1024x683.jpg","datePublished":"2024-03-28T08:16:29+00:00","dateModified":"2024-03-28T10:46:23+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#\/schema\/person\/9f23ca3c7e8761fd1498ca155fa97be5"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/files\/2024\/03\/20240328_MiG_Bild1.jpg","width":1261,"height":841},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/2024\/03\/28\/lernen-sie-noch-oder-spielen-sie-schon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/"},{"@type":"ListItem","position":2,"name":"Lernen Sie noch oder spielen Sie schon?"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#website","url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/","name":"Gesundheits\u00f6konomie @ ZHAW","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/#\/schema\/person\/9f23ca3c7e8761fd1498ca155fa97be5","name":"Gesundheits\u00f6konomie @ ZHAW","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/288a1d08b0bf4c2e06b5b02bcb8c585ab944f18ce54a408ddc9104152dd07117?s=96&d=mm&r=g","caption":"Gesundheits\u00f6konomie @ ZHAW"},"url":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/author\/grbd\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/posts\/3768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/users\/394"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/comments?post=3768"}],"version-history":[{"count":9,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/posts\/3768\/revisions"}],"predecessor-version":[{"id":3779,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/posts\/3768\/revisions\/3779"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/media?parent=3768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/categories?post=3768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/tags?post=3768"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/gesundheitsoekonomie\/wp-json\/wp\/v2\/features?post=3768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}