{"id":733,"date":"2017-04-27T15:08:16","date_gmt":"2017-04-27T13:08:16","guid":{"rendered":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?p=733"},"modified":"2017-04-27T16:37:28","modified_gmt":"2017-04-27T14:37:28","slug":"die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/","title":{"rendered":"&#8222;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&#8220;"},"content":{"rendered":"<p><a href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-735 size-large\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg\" alt=\"\" height=\"448\" width=\"584\" srcset=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg 1024w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-300x230.jpg 300w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-768x590.jpg 768w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-391x300.jpg 391w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a>Patrik Deuss, Gr\u00fcnder von LEDCity<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>In zwei \u2013 drei S\u00e4tzen, was macht LEDCity?<br \/>\n<\/em><\/strong>LEDCity entwickelt automatisierte Leuchtmittel mit dem Ziel, den Energieverbrauch im Beleuchtungssektor signifikant zu reduzieren. Durch die Automatisation ver\u00e4ndern die Leuchtmittel die Helligkeit dynamisch und werden nicht rund um die Uhr unter Volllast betrieben. Das bet\u00e4tigen eines Lichtschalters soll der Vergangenheit angeh\u00f6ren.<\/p>\n<p><strong><em>Ihr seid nun nach 9 Monaten aus dem <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\">RUNWAY<\/a> ausgetreten. Wie geht es weiter?<br \/>\n<\/em><\/strong>Ab dem 1. Mai geht es in den Technopark Z\u00fcrich, wo wir unser eigenes B\u00fcro beziehen werden. Die Wahl fiel auf Z\u00fcrich \u2013 nicht zuletzt aus praktischen Gr\u00fcnden, denn Z\u00fcrich ist f\u00fcr alle Teammitglieder am einfachsten zu erreichen.<br \/>\nAbgesehen hiervon, sind wir derzeit in den letzten Z\u00fcgen der AG-Gr\u00fcndung. Die n\u00e4chsten Schritte sind weitere Pilotprojekte, kleinere Anpassungen am Prototypen und dann geht es mit dem finalen Produkt auf den Markt.<\/p>\n<p><strong><em>Gehen wir mal ein paar Monate zur\u00fcck, wie ist die Idee zu LEDCity entstanden?<\/em><br \/>\n<\/strong>Alles begann w\u00e4hrend einer Vorlesung im Studiengang <em>Energie- und Umwelttechnik<\/em>. Mir wurde bewusst, dass es noch viel Potential im Beleuchtungssektor gibt, um durch die dynamische Verwendung des Lichts Energie zu sparen. Man l\u00e4sst zu Hause nicht die ganze Nacht das Licht an, wieso tut man es dann draussen, z.B. in Tunnels? Es macht energetisch gesehen einen riesen Unterschied, ob man einen Tunnel 24 Stunden beleuchtet oder nur 24 Minuten, wenn es tats\u00e4chlich gebraucht wird \u2013 n\u00e4mlich Faktor 60.<\/p>\n<p>Nach einer kurzen Zeit, konnte ich mein Team um einen Studienkollegen erweitern. Ziemlich schnell ging es dann weiter zur <a href=\"https:\/\/www.zhaw.ch\/en\/research\/entrepreneurship-at-the-zhaw\/entrepreneurshipzhaw\/startup-challenge\/\"><em>ZHAW Startup Challenge<\/em><\/a>, welche uns dann von der Uni in die Arbeitswelt katapultierte. Wir machten den zweiten Platz und gewannen eine sechs-monatige kostenlose Mitgliedschaft im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY Incubator<\/em><\/a>. Wir beide haben keinen Business-Hintergrund und diese ganze Zeit, war f\u00fcr uns wie eine Art Express-BWL-Studium. Das Coaching von Thomas Schumann, die Unterst\u00fctzung von Adrian M\u00fcller, Jacques Hefti, Nicolas Gehrig, Alex von Siebenthal und Yasemin Ayanoglu waren sehr wertvoll f\u00fcr uns und ich m\u00f6chte mich an dieser Stelle gerne bei allen ganz herzlich bedanken! Auch der rege Austausch mit den anderen Startups im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY<\/em><\/a> hat uns sehr geholfen und uns inspiriert \u2013 auch hier ein Dankesch\u00f6n an alle.<\/p>\n<p><strong><em>Was waren wichtige Schritte oder Milestones f\u00fcr euch?<\/em><\/strong><br \/>\nEines der ersten Milestones war sicherlich die Bachelorarbeit zum Thema: &#8222;Entwicklung einer interaktiven LED-Steuerung&#8220;. Diese wurde damals Dank der Einwilligung der Professoren Borth und Heinzelmann erm\u00f6glicht.<br \/>\nWeitere wichtige Schritte waren die <a href=\"https:\/\/www.zhaw.ch\/en\/research\/entrepreneurship-at-the-zhaw\/entrepreneurshipzhaw\/startup-challenge\/\"><em>ZHAW Startup Challenge<\/em><\/a> und die Aufnahme im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY<\/em><\/a>, das Pilotprojekt mit der <a href=\"https:\/\/www.ewz.ch\/de\/private.html\"><em>ewz<\/em><\/a>, die Finanzspritze von der <a href=\"https:\/\/www.klimastiftung.ch\/de\/\"><em>Klimastiftung Schweiz<\/em> <\/a>und dem <a href=\"http:\/\/www.bfe.admin.ch\/\"><em>Bundesamt f\u00fcr Energie<\/em><\/a> und schliesslich die Erstellung des zweiten Prototyps, das dem Endprodukt schon sehr nahekommt.<\/p>\n<p><strong><em>Wie hast du die Zeit im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\">RUNWAY<\/a> empfunden und w\u00fcrdest du es anderen weiterempfehlen?<br \/>\n<\/em><\/strong>Auf jeden Fall. Das Umfeld im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY<\/em><\/a> wie auch im <a href=\"http:\/\/tpw.ch\/\"><em>Technopark Winterthur<\/em><\/a> ist sehr inspirierend, man erh\u00e4lt viel Unterst\u00fctzung, bei Fragen ist immer jemand erreichbar, die Infrastruktur ist super \u2026 eindeutig ja.<\/p>\n<p><strong><em>Was sind die gr\u00f6ssten Learnings aus deiner Zeit im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\">RUNWAY<\/a>?<br \/>\n<\/em><\/strong>Ich habe sehr viel im Business Bereich gelernt. Auch habe ich gelernt Feedback aufzunehmen und richtig einzuordnen. Es gibt Leute, die sagen \u00abaus deiner Idee wird nichts\u00bb, andere sind wiederum total begeistert\u2026 Da ist es wichtig ein Gef\u00fchl daf\u00fcr zu entwickeln, wichtige Punkte aus dem Feedback herauszuziehen und sich von negativen Meinungen nicht herunterziehen zu lassen. Damit einher geht auch Ausdauer. Ein weiteres Learning aus meiner Zeit im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY<\/em><\/a>. Es kann nur weitergehen, wenn man dranbleibt und an seine Idee glaubt. Dann glauben auch andere daran und es finden sich auch Gelder, wie z.B. bei uns die Finanzspritze von der <a href=\"https:\/\/www.klimastiftung.ch\/de\/\"><em>Klimastiftung Schweiz<\/em><\/a> und dem <a href=\"http:\/\/www.bfe.admin.ch\/\"><em>Bundesamt f\u00fcr Energie<\/em><\/a>.<\/p>\n<p><strong><em>Wenn du nun zur\u00fcckblickst, w\u00fcrdest du etwas anders machen?<\/em><\/strong><br \/>\nIch w\u00fcrde von Anfang an schauen, dass ich ein gutes Team zusammenstelle, bestehend aus Leuten, die ebenfalls 100 % dabei sind und nicht zu viele andere Verpflichtungen haben. Auch w\u00fcrde ich schauen, dass es ein durchmischtes Team ist, sodass das Kernteam bereits verschiedene Bereiche abdeckt und nicht alle den gleichen Hintergrund haben.<br \/>\nMan h\u00f6rt es oft, dennoch ich m\u00f6chte es auch nochmal sagen: Fokus! Man muss nicht jedes kleine Feedback sofort in das Produkt einarbeiten, sondern das grosse Ganze sehen. Damit einhergeht auch die richtige Priorisierung der anstehenden Aufgaben. Das musste ich erst lernen.<\/p>\n<p><strong><em>W\u00fcrdest du anderen empfehlen, ein Startup zu gr\u00fcnden?<br \/>\n<\/em><\/strong>Auf jeden Fall. Wieso denn auch nicht? Versuchen kann man es ja mal und man lernt nur dazu. Als Angestellte\/r arbeiten, kann man danach immer noch.<\/p>\n<p><strong><em>Was w\u00fcrdest du anderen potentiellen Gr\u00fcndern mitgeben?<br \/>\n<\/em><\/strong>In der Schweiz ist man finanziell gut abgesichert. Es ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren. Es gibt unglaublich viele M\u00f6glichkeiten sich Unterst\u00fctzung zu holen \u2013 wie z.B. im <a href=\"https:\/\/www.zhaw.ch\/de\/forschung\/entrepreneurship-an-der-zhaw\/entrepreneurship\/runway\/\"><em>RUNWAY Incubator<\/em><\/a>. Riskiert \u2013 probiert \u2013 lernt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Patrik Deuss, Gr\u00fcnder von LEDCity &nbsp; In zwei \u2013 drei S\u00e4tzen, was macht LEDCity? LEDCity entwickelt automatisierte Leuchtmittel mit dem Ziel, den Energieverbrauch im Beleuchtungssektor signifikant zu reduzieren. Durch die Automatisation ver\u00e4ndern die Leuchtmittel die Helligkeit dynamisch und werden nicht rund um die Uhr unter Volllast betrieben. Das bet\u00e4tigen eines Lichtschalters soll der Vergangenheit angeh\u00f6ren. [&hellip;]<\/p>\n","protected":false},"author":295,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10,34,35],"tags":[],"features":[],"class_list":["post-733","post","type-post","status-publish","format-standard","hentry","category-entrepreneurial-skills","category-runway-startup","category-zhaw-startup-challenge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&quot; - Entrepreneurship\u00ad@zhaw Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&quot;\" \/>\n<meta property=\"og:description\" content=\"Patrik Deuss, Gr\u00fcnder von LEDCity &nbsp; In zwei \u2013 drei S\u00e4tzen, was macht LEDCity? LEDCity entwickelt automatisierte Leuchtmittel mit dem Ziel, den Energieverbrauch im Beleuchtungssektor signifikant zu reduzieren. Durch die Automatisation ver\u00e4ndern die Leuchtmittel die Helligkeit dynamisch und werden nicht rund um die Uhr unter Volllast betrieben. Das bet\u00e4tigen eines Lichtschalters soll der Vergangenheit angeh\u00f6ren. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Entrepreneurship\u00ad@zhaw Blog\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-27T13:08:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-27T14:37:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/\"},\"author\":{\"name\":\"Anna-Maria Str\u00e4ssner\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"headline\":\"&#8222;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&#8220;\",\"datePublished\":\"2017-04-27T13:08:16+00:00\",\"dateModified\":\"2017-04-27T14:37:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/\"},\"wordCount\":833,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/04\\\/Patrik3cut_2-1024x786.jpg\",\"articleSection\":[\"Entrepreneurial Skills\",\"RUNWAY Startup\",\"ZHAW Startup Challenge\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/\",\"name\":\"\\\"Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.\\\" - Entrepreneurship\u00ad@zhaw Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/04\\\/Patrik3cut_2-1024x786.jpg\",\"datePublished\":\"2017-04-27T13:08:16+00:00\",\"dateModified\":\"2017-04-27T14:37:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/04\\\/Patrik3cut_2.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/04\\\/Patrik3cut_2.jpg\",\"width\":2655,\"height\":2038},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\",\"name\":\"Entrepreneurship\u00ad@zhaw Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\",\"name\":\"Anna-Maria Str\u00e4ssner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"caption\":\"Anna-Maria Str\u00e4ssner\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/author\\\/stsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.\" - Entrepreneurship\u00ad@zhaw Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/","og_locale":"de_DE","og_type":"article","og_title":"\"Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.\"","og_description":"Patrik Deuss, Gr\u00fcnder von LEDCity &nbsp; In zwei \u2013 drei S\u00e4tzen, was macht LEDCity? LEDCity entwickelt automatisierte Leuchtmittel mit dem Ziel, den Energieverbrauch im Beleuchtungssektor signifikant zu reduzieren. Durch die Automatisation ver\u00e4ndern die Leuchtmittel die Helligkeit dynamisch und werden nicht rund um die Uhr unter Volllast betrieben. Das bet\u00e4tigen eines Lichtschalters soll der Vergangenheit angeh\u00f6ren. [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/","og_site_name":"Entrepreneurship\u00ad@zhaw Blog","article_published_time":"2017-04-27T13:08:16+00:00","article_modified_time":"2017-04-27T14:37:28+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg","type":"","width":"","height":""}],"author":"Anna-Maria Str\u00e4ssner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna-Maria Str\u00e4ssner","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/"},"author":{"name":"Anna-Maria Str\u00e4ssner","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"headline":"&#8222;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&#8220;","datePublished":"2017-04-27T13:08:16+00:00","dateModified":"2017-04-27T14:37:28+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/"},"wordCount":833,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg","articleSection":["Entrepreneurial Skills","RUNWAY Startup","ZHAW Startup Challenge"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/","name":"\"Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.\" - Entrepreneurship\u00ad@zhaw Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2-1024x786.jpg","datePublished":"2017-04-27T13:08:16+00:00","dateModified":"2017-04-27T14:37:28+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/04\/Patrik3cut_2.jpg","width":2655,"height":2038},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/die-schweiz-ist-der-perfekte-ort-um-zu-gruenden-und-auch-mal-etwas-zu-riskieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/entrepreneurship\/"},{"@type":"ListItem","position":2,"name":"&#8220;Die Schweiz ist der perfekte Ort, um zu gr\u00fcnden und auch mal etwas zu riskieren.&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/","name":"Entrepreneurship\u00ad@zhaw Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323","name":"Anna-Maria Str\u00e4ssner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","caption":"Anna-Maria Str\u00e4ssner"},"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/author\/stsn\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/users\/295"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/comments?post=733"}],"version-history":[{"count":7,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/733\/revisions"}],"predecessor-version":[{"id":741,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/733\/revisions\/741"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/media?parent=733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/categories?post=733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/tags?post=733"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/features?post=733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}