{"id":721,"date":"2017-03-08T13:38:56","date_gmt":"2017-03-08T12:38:56","guid":{"rendered":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?p=721"},"modified":"2017-03-08T13:38:56","modified_gmt":"2017-03-08T12:38:56","slug":"zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/","title":{"rendered":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten"},"content":{"rendered":"<p><strong>Nach Klimastiftung Schweiz \u2013 Unterst\u00fctzung vom Bundesamt f\u00fcr Energie<\/strong><\/p>\n<p><a href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-723 size-large\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg\" alt=\"\" height=\"388\" width=\"584\" srcset=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg 1024w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-300x199.jpg 300w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-768x510.jpg 768w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-452x300.jpg 452w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity.jpg 1386w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n<p>In der Schweiz entfallen rund 12 % des Elektrizit\u00e4tsverbrauches auf die Erzeugung von Licht. Dies entspricht der Leistung von rund 1.5 Atomkraftwerken. Mithilfe einer Steigerung der Leuchteffizienz, durch Automatisation und k\u00fcnstliche Intelligenz soll der Verbrauch in den n\u00e4chsten 10 Jahren um bis zu 80 % reduziert werden. Zum Vergleich: Wenn alle Fahrzeuge in der Schweiz elektrisch angetrieben werden, w\u00fcrde der Elektrizit\u00e4tsverbrauch um rund 15 % ansteigen. Die Energiereduktion im Lichtsektor w\u00fcrde daher der Elektromobilit\u00e4t in die H\u00e4nde spielen.<\/p>\n<p>Um dieses Ziel zu erreichen hat nach der Klimastiftung Schweiz auch das Bundesamt f\u00fcr Energie das Potential in LEDCity entdeckt und eine Finanzspritze gutgeheissen. Mit dem Betrag von 94\u2018825.- steigt die F\u00f6rderung auf knapp eine Viertelmillion CHF.&nbsp;<\/p>\n<p>LEDCity ist ein Schweizer Startup der ZHAW welches interaktive und dynamische LED-Leuchtmittel entwickelt. Die intelligenten Leuchtmittel &nbsp;k\u00f6nnen selber entscheiden, wo wieviel Licht ben\u00f6tigt wird. Noch zu viele Tunnel, Unterf\u00fchrungen, G\u00e4nge und viele weitere Standorte werden rund um die Uhr beleuchtet. Kann die Nutzungsdauer nur schon um einige Stunden reduziert werden, sinkt der Energieverbrauch signifikant. In der Praxis konnten bei Projekten jeweils zwischen 65-90 % der Energie eingespart werden.<\/p>\n<p>Schon im n\u00e4chsten Monat sollen die Arbeiten f\u00fcr eine neue Pilotanlage mit dem ewz starten. Mehrere Grossunternehmen haben bereits ihr Interesse f\u00fcr die innovative L\u00f6sung ge\u00e4ussert und werden ebenfalls in diesem Fr\u00fchling eigene Pilotanlagen in Betrieb nehmen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach Klimastiftung Schweiz \u2013 Unterst\u00fctzung vom Bundesamt f\u00fcr Energie In der Schweiz entfallen rund 12 % des Elektrizit\u00e4tsverbrauches auf die Erzeugung von Licht. Dies entspricht der Leistung von rund 1.5 Atomkraftwerken. Mithilfe einer Steigerung der Leuchteffizienz, durch Automatisation und k\u00fcnstliche Intelligenz soll der Verbrauch in den n\u00e4chsten 10 Jahren um bis zu 80 % reduziert [&hellip;]<\/p>\n","protected":false},"author":295,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,13,34,35],"tags":[],"features":[],"class_list":["post-721","post","type-post","status-publish","format-standard","hentry","category-cti-entrepreneurship","category-entrepreneurshipzhaw","category-runway-startup","category-zhaw-startup-challenge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ZHAW Startup LEDCity hat weitere Finanzspritze erhalten - Entrepreneurship\u00ad@zhaw Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten\" \/>\n<meta property=\"og:description\" content=\"Nach Klimastiftung Schweiz \u2013 Unterst\u00fctzung vom Bundesamt f\u00fcr Energie In der Schweiz entfallen rund 12 % des Elektrizit\u00e4tsverbrauches auf die Erzeugung von Licht. Dies entspricht der Leistung von rund 1.5 Atomkraftwerken. Mithilfe einer Steigerung der Leuchteffizienz, durch Automatisation und k\u00fcnstliche Intelligenz soll der Verbrauch in den n\u00e4chsten 10 Jahren um bis zu 80 % reduziert [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/\" \/>\n<meta property=\"og:site_name\" content=\"Entrepreneurship\u00ad@zhaw Blog\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-08T12:38:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/\"},\"author\":{\"name\":\"Anna-Maria Str\u00e4ssner\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"headline\":\"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten\",\"datePublished\":\"2017-03-08T12:38:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/\"},\"wordCount\":251,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/03\\\/ledcity-1024x680.jpg\",\"articleSection\":[\"CTI Entrepreneurship\",\"Entrepreneurship@ZHAW\",\"RUNWAY Startup\",\"ZHAW Startup Challenge\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/\",\"name\":\"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten - Entrepreneurship\u00ad@zhaw Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/03\\\/ledcity-1024x680.jpg\",\"datePublished\":\"2017-03-08T12:38:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/03\\\/ledcity.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2017\\\/03\\\/ledcity.jpg\",\"width\":1386,\"height\":920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\",\"name\":\"Entrepreneurship\u00ad@zhaw Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\",\"name\":\"Anna-Maria Str\u00e4ssner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"caption\":\"Anna-Maria Str\u00e4ssner\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/author\\\/stsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten - Entrepreneurship\u00ad@zhaw Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/","og_locale":"de_DE","og_type":"article","og_title":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten","og_description":"Nach Klimastiftung Schweiz \u2013 Unterst\u00fctzung vom Bundesamt f\u00fcr Energie In der Schweiz entfallen rund 12 % des Elektrizit\u00e4tsverbrauches auf die Erzeugung von Licht. Dies entspricht der Leistung von rund 1.5 Atomkraftwerken. Mithilfe einer Steigerung der Leuchteffizienz, durch Automatisation und k\u00fcnstliche Intelligenz soll der Verbrauch in den n\u00e4chsten 10 Jahren um bis zu 80 % reduziert [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/","og_site_name":"Entrepreneurship\u00ad@zhaw Blog","article_published_time":"2017-03-08T12:38:56+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg","type":"","width":"","height":""}],"author":"Anna-Maria Str\u00e4ssner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna-Maria Str\u00e4ssner","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/"},"author":{"name":"Anna-Maria Str\u00e4ssner","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"headline":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten","datePublished":"2017-03-08T12:38:56+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/"},"wordCount":251,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg","articleSection":["CTI Entrepreneurship","Entrepreneurship@ZHAW","RUNWAY Startup","ZHAW Startup Challenge"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/","name":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten - Entrepreneurship\u00ad@zhaw Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity-1024x680.jpg","datePublished":"2017-03-08T12:38:56+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2017\/03\/ledcity.jpg","width":1386,"height":920},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-ledcity-hat-weitere-finanzspritze-erhalten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/entrepreneurship\/"},{"@type":"ListItem","position":2,"name":"ZHAW Startup LEDCity hat weitere Finanzspritze erhalten"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/","name":"Entrepreneurship\u00ad@zhaw Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323","name":"Anna-Maria Str\u00e4ssner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","caption":"Anna-Maria Str\u00e4ssner"},"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/author\/stsn\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/users\/295"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/comments?post=721"}],"version-history":[{"count":9,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/721\/revisions"}],"predecessor-version":[{"id":731,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/721\/revisions\/731"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/media?parent=721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/categories?post=721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/tags?post=721"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/features?post=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}