{"id":675,"date":"2016-10-07T15:34:27","date_gmt":"2016-10-07T13:34:27","guid":{"rendered":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?p=675"},"modified":"2016-10-07T15:36:07","modified_gmt":"2016-10-07T13:36:07","slug":"aktuelle-erkenntnisse-aus-der-energieforschung","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/","title":{"rendered":"Aktuelle Erkenntnisse aus der Energieforschung"},"content":{"rendered":"<p><a href=\"https:\/\/blog.zhaw.ch\/forschungssupport\/crest-annual-conference-2016\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-677 size-full\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg\" alt=\"sccer-crest-conference\" width=\"631\" height=\"313\" srcset=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg 631w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference-300x149.jpg 300w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference-500x248.jpg 500w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":295,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"features":[],"class_list":["post-675","post","type-post","status-publish","format-aside","hentry","category-events","post_format-post-format-aside"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aktuelle Erkenntnisse aus der Energieforschung - Entrepreneurship\u00ad@zhaw Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktuelle Erkenntnisse aus der Energieforschung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/\" \/>\n<meta property=\"og:site_name\" content=\"Entrepreneurship\u00ad@zhaw Blog\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-07T13:34:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-07T13:36:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/\"},\"author\":{\"name\":\"Anna-Maria Str\u00e4ssner\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"headline\":\"Aktuelle Erkenntnisse aus der Energieforschung\",\"datePublished\":\"2016-10-07T13:34:27+00:00\",\"dateModified\":\"2016-10-07T13:36:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/\"},\"wordCount\":5,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/10\\\/SCCER-CREST-Conference.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/\",\"name\":\"Aktuelle Erkenntnisse aus der Energieforschung - Entrepreneurship\u00ad@zhaw Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/10\\\/SCCER-CREST-Conference.jpg\",\"datePublished\":\"2016-10-07T13:34:27+00:00\",\"dateModified\":\"2016-10-07T13:36:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/10\\\/SCCER-CREST-Conference.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/10\\\/SCCER-CREST-Conference.jpg\",\"width\":631,\"height\":313},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/aktuelle-erkenntnisse-aus-der-energieforschung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuelle Erkenntnisse aus der Energieforschung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\",\"name\":\"Entrepreneurship\u00ad@zhaw Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\",\"name\":\"Anna-Maria Str\u00e4ssner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"caption\":\"Anna-Maria Str\u00e4ssner\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/author\\\/stsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aktuelle Erkenntnisse aus der Energieforschung - Entrepreneurship\u00ad@zhaw Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/","og_locale":"de_DE","og_type":"article","og_title":"Aktuelle Erkenntnisse aus der Energieforschung","og_url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/","og_site_name":"Entrepreneurship\u00ad@zhaw Blog","article_published_time":"2016-10-07T13:34:27+00:00","article_modified_time":"2016-10-07T13:36:07+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg","type":"","width":"","height":""}],"author":"Anna-Maria Str\u00e4ssner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna-Maria Str\u00e4ssner"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/"},"author":{"name":"Anna-Maria Str\u00e4ssner","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"headline":"Aktuelle Erkenntnisse aus der Energieforschung","datePublished":"2016-10-07T13:34:27+00:00","dateModified":"2016-10-07T13:36:07+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/"},"wordCount":5,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg","articleSection":["Events"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/","name":"Aktuelle Erkenntnisse aus der Energieforschung - Entrepreneurship\u00ad@zhaw Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg","datePublished":"2016-10-07T13:34:27+00:00","dateModified":"2016-10-07T13:36:07+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/10\/SCCER-CREST-Conference.jpg","width":631,"height":313},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/aktuelle-erkenntnisse-aus-der-energieforschung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/entrepreneurship\/"},{"@type":"ListItem","position":2,"name":"Aktuelle Erkenntnisse aus der Energieforschung"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/","name":"Entrepreneurship\u00ad@zhaw Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323","name":"Anna-Maria Str\u00e4ssner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","caption":"Anna-Maria Str\u00e4ssner"},"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/author\/stsn\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/users\/295"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/comments?post=675"}],"version-history":[{"count":4,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/675\/revisions"}],"predecessor-version":[{"id":680,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/675\/revisions\/680"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/media?parent=675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/categories?post=675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/tags?post=675"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/features?post=675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}