{"id":457,"date":"2016-03-02T15:06:50","date_gmt":"2016-03-02T14:06:50","guid":{"rendered":"https:\/\/blog.zhaw.ch\/cie\/?p=457"},"modified":"2016-03-22T11:39:09","modified_gmt":"2016-03-22T10:39:09","slug":"myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/","title":{"rendered":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-460\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png\" alt=\"Banner_MAS_launch\" width=\"584\" height=\"238\" \/><\/p>\n<p>Hast du schon immer einmal davon getr\u00e4umt, in einem Kleinflugzeug das Schweizer Bergpanorama zu erleben? Das Startup MyAirSeat, welches im RUNWAY Startup Incubator der ZHAW beheimatet ist, macht dies seit wenigen Tagen m\u00f6glich.<\/p>\n<p>MyAirSeat bietet als erste App das Buchen von Mitfahrgelegenheiten einige hundert Meter \u00fcber Boden an und verbindet so Flug-Unternehmen mit Passagieren. Per Kartenansicht kann man sich bequem \u00fcber einzelne Sitzpl\u00e4tze in Flieger informieren. Ein 20-min\u00fctiger Rundflug um den Thunersee von Swisshelicopter ist beispielsweise f\u00fcr CHF 180 zu haben.<\/p>\n<p>Die App ist kostenlos im iTunes oder Google Store f\u00fcr iPhone und Android Handys verf\u00fcgbar. <a href=\"https:\/\/itunes.apple.com\/us\/app\/myairseat\/id1033840839?mt=8\">https:\/\/itunes.apple.com\/us\/app\/myairseat\/id1033840839?mt=8<\/a><\/p>\n<p><strong>Steckbrief<br \/>\n<\/strong><a href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/03\/Steckbrief-MyAirSeat-1.png\" rel=\"attachment wp-att-497\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-497\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/03\/Steckbrief-MyAirSeat-1-1024x724.png\" alt=\"Steckbrief MyAirSeat\" width=\"280\" height=\"200\" \/><\/a><\/p>\n<p><strong>F\u00fcnf Fragen an die Gr\u00fcnder: <\/strong><\/p>\n<p><strong>Was ist euer Hintergrund? Wie seid ihr auf die Idee gekommen?<br \/>\n<\/strong>Wir sind beide Helikopterpiloten und Philipp ist Anwalt und Verwaltungsrat bei Air Zermatt. Immer wieder haben wir uns gefragt, warum Fl\u00fcge noch nicht elektronisch gebucht werden k\u00f6nnen \u2013 dies packen wir nun an!<\/p>\n<p><strong>Was wollt ihr mit eurem Vorhaben bewirken? Was motiviert euch?<br \/>\n<\/strong>Mit dem Buchungssystem soll der administrative Aufwand auf Seite der Flugunternehmen verkleinert werden (bis jetzt werden Anfragen nur per Telefon angenommen)<\/p>\n<p><strong>Arbeitet ihr Voll- oder Teilzeit an eurer Idee? Wie geht ihr mit der Arbeitsbelastung um?<br \/>\n<\/strong>Alexander (CEO) arbeitet 50% neben seinem Studium daran \/ Thomas (Pr\u00e4sident) ca. 20-30% je nach Bedarf \/ Philipp (Partner Legal &amp; Compliance) bei Bedarf ebenfalls 10-20%<\/p>\n<p><strong>Wo m\u00f6chtet ihr in 3 Jahren stehen?<br \/>\n<\/strong>In 3 Jahren soll MyAirSeat die Nummer 1 weltweit zur Buchung von Helikopter- und Kleinflugzeugfl\u00fcgen sein<\/p>\n<p><strong>Warum sollte jemand in euer Startup investieren?<br \/>\n<\/strong>Das Bed\u00fcrfnis nach Mobilit\u00e4t und Abenteuer steigt! Die Kleinfliegerei ist noch nicht ins Verkehrsnetz oder bestehende Bookingplattformen integriert \u2013 wir treffen mit unserem Offering also direkt ins Schwarze.<\/p>\n<p><em>Follow MyAirSeat\u00a0on Linkedin: <\/em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/www.linkedin.com\/company\/myairseat\">https:\/\/www.linkedin.com\/company\/myairseat<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hast du schon immer einmal davon getr\u00e4umt, in einem Kleinflugzeug das Schweizer Bergpanorama zu erleben? Das Startup MyAirSeat, welches im RUNWAY Startup Incubator der ZHAW beheimatet ist, macht dies seit wenigen Tagen m\u00f6glich. MyAirSeat bietet als erste App das Buchen von Mitfahrgelegenheiten einige hundert Meter \u00fcber Boden an und verbindet so Flug-Unternehmen mit Passagieren. Per [&hellip;]<\/p>\n","protected":false},"author":206,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[34],"tags":[],"features":[],"class_list":["post-457","post","type-post","status-publish","format-standard","hentry","category-runway-startup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter - Entrepreneurship\u00ad@zhaw Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter\" \/>\n<meta property=\"og:description\" content=\"Hast du schon immer einmal davon getr\u00e4umt, in einem Kleinflugzeug das Schweizer Bergpanorama zu erleben? Das Startup MyAirSeat, welches im RUNWAY Startup Incubator der ZHAW beheimatet ist, macht dies seit wenigen Tagen m\u00f6glich. MyAirSeat bietet als erste App das Buchen von Mitfahrgelegenheiten einige hundert Meter \u00fcber Boden an und verbindet so Flug-Unternehmen mit Passagieren. Per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/\" \/>\n<meta property=\"og:site_name\" content=\"Entrepreneurship\u00ad@zhaw Blog\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-02T14:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-22T10:39:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png\" \/>\n<meta name=\"author\" content=\"susa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"susa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/\"},\"author\":{\"name\":\"susa\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/7226a80a39ab979bf8d47477cdbbefe2\"},\"headline\":\"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter\",\"datePublished\":\"2016-03-02T14:06:50+00:00\",\"dateModified\":\"2016-03-22T10:39:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/\"},\"wordCount\":309,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/02\\\/Banner_MAS_launch-1024x417.png\",\"articleSection\":[\"RUNWAY Startup\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/\",\"name\":\"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter - Entrepreneurship\u00ad@zhaw Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/02\\\/Banner_MAS_launch-1024x417.png\",\"datePublished\":\"2016-03-02T14:06:50+00:00\",\"dateModified\":\"2016-03-22T10:39:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/7226a80a39ab979bf8d47477cdbbefe2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/02\\\/Banner_MAS_launch-1024x417.png\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2016\\\/02\\\/Banner_MAS_launch-1024x417.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\",\"name\":\"Entrepreneurship\u00ad@zhaw Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/7226a80a39ab979bf8d47477cdbbefe2\",\"name\":\"susa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g\",\"caption\":\"susa\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/author\\\/isen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter - Entrepreneurship\u00ad@zhaw Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/","og_locale":"de_DE","og_type":"article","og_title":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter","og_description":"Hast du schon immer einmal davon getr\u00e4umt, in einem Kleinflugzeug das Schweizer Bergpanorama zu erleben? Das Startup MyAirSeat, welches im RUNWAY Startup Incubator der ZHAW beheimatet ist, macht dies seit wenigen Tagen m\u00f6glich. MyAirSeat bietet als erste App das Buchen von Mitfahrgelegenheiten einige hundert Meter \u00fcber Boden an und verbindet so Flug-Unternehmen mit Passagieren. Per [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/","og_site_name":"Entrepreneurship\u00ad@zhaw Blog","article_published_time":"2016-03-02T14:06:50+00:00","article_modified_time":"2016-03-22T10:39:09+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png","type":"","width":"","height":""}],"author":"susa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"susa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/"},"author":{"name":"susa","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/7226a80a39ab979bf8d47477cdbbefe2"},"headline":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter","datePublished":"2016-03-02T14:06:50+00:00","dateModified":"2016-03-22T10:39:09+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/"},"wordCount":309,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png","articleSection":["RUNWAY Startup"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/","name":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter - Entrepreneurship\u00ad@zhaw Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png","datePublished":"2016-03-02T14:06:50+00:00","dateModified":"2016-03-22T10:39:09+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/7226a80a39ab979bf8d47477cdbbefe2"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png","contentUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2016\/02\/Banner_MAS_launch-1024x417.png"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/myairseat-mitfluggelegenheit-fuer-kleinflugzeuge-und-helikopter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/entrepreneurship\/"},{"@type":"ListItem","position":2,"name":"MyAirSeat \u2013 Mitfluggelegenheit f\u00fcr Kleinflugzeuge und Helikopter"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/","name":"Entrepreneurship\u00ad@zhaw Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/7226a80a39ab979bf8d47477cdbbefe2","name":"susa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0cfd10ed22674d85e500e4eb26f0288a29cd47a4a998338df14f74ab9f563a45?s=96&d=mm&r=g","caption":"susa"},"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/author\/isen\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/users\/206"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":8,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/457\/revisions"}],"predecessor-version":[{"id":498,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/457\/revisions\/498"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/media?parent=457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/categories?post=457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/tags?post=457"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/features?post=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}