{"id":1248,"date":"2020-01-15T10:35:57","date_gmt":"2020-01-15T09:35:57","guid":{"rendered":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?p=1248"},"modified":"2020-01-15T12:55:06","modified_gmt":"2020-01-15T11:55:06","slug":"zhaw-startup-challenge-2020-es-geht-los","status":"publish","type":"post","link":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/","title":{"rendered":"Jetzt anmelden zur ZHAW Startup Challenge 2020!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die ZHAW Startup Challenge geht 2020 in die sechste Runde! Bist du mit dabei? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ab sofort  k\u00f6nnen sich unternehmerisch interessierte Studierende und Angeh\u00f6rige der gesamten ZHAW zur j\u00e4hrlichen <a href=\"http:\/\/www.startup-challenge.ch\">Startup Challenge<\/a> anmelden und erste Startup-Luft schnuppern. Eine Gelegenheit, die ihr euch auf keinen Fall entgehen lassen solltet. Neben wertvollem Wissen \u00fcber Start-ups und dem Ausprobieren unternehmerischen Denkens, ist eine Menge Spass garantiert! Wir freuen uns auf alle, die 2020 bei der Challenge dabei sind und sich trauen, \u00fcber den &#8222;Tellerrand&#8220; des Studienalltags hinauszuschauen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meldet Euch einfach f\u00fcr einen der <a href=\"https:\/\/podio.com\/webforms\/17626473\/1184793\">Kick-Off Events<\/a> an und erfahrt alles Weitere vor Ort.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Campus Winterthur, 23. M\u00e4rz um 18 Uhr oder<\/li><li>Campus W\u00e4denswil, 24. M\u00e4rz um 18 Uhr oder<\/li><li>Campus Z\u00fcrich, 25. M\u00e4rz um 18 Uhr<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"1024\" src=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg\" alt=\"\" class=\"wp-image-1249\" srcset=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg 791w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-232x300.jpg 232w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-768x994.jpg 768w, https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-676x875.jpg 676w\" sizes=\"auto, (max-width: 791px) 100vw, 791px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Keine Ahnung von der Startup-Welt?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kein Problem! \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bieten zwei unverbindliche Einf\u00fchrungs-Sessions an, die euch die \nBegrifflichkeiten und Besonderheiten der Startup-Welt auf einfache Weise\n n\u00e4herbringen und erkl\u00e4ren. \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Sessions sind eine gute Vorbereitung f\u00fcr die ZHAW Startup \nChallenge und alle Studierenden, die sich erstmals mit dem Thema \nbefassen. Anmeldung erforderlich, da begrenzte Pl\u00e4tze.\n<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab<strong>Startup ABC<\/strong>\u00bb \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von Bootstrapping \u00fcber Inkubation bis Pitching und Venture Capital &#8211; \nWir f\u00fchren euch in den Startup-Jargon ein und erkl\u00e4ren euch die \nwichtigsten Begriffe.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">04. M\u00e4rz, 17-19 Uhr, Standort Z\u00fcrich, Anmeldung <a href=\"https:\/\/podio.com\/webforms\/20455839\/1399330\">HIER<\/a>\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abHow to business model canvas\u00bb<\/strong>\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was ist das Business Model Canvas \u00fcberhaupt und wie und wof\u00fcr wird es\n angewendet? Wir zeigen es euch und geben euch eine Einf\u00fchrung.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11. M\u00e4rz, 17-19 Uhr, Standort Z\u00fcrich, Anmeldung <a href=\"https:\/\/podio.com\/webforms\/20455839\/1399330\">HIER<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ZHAW Startup Challenge geht 2020 in die sechste Runde! Bist du mit dabei? Ab sofort k\u00f6nnen sich unternehmerisch interessierte Studierende und Angeh\u00f6rige der gesamten ZHAW zur j\u00e4hrlichen Startup Challenge anmelden und erste Startup-Luft schnuppern. Eine Gelegenheit, die ihr euch auf keinen Fall entgehen lassen solltet. Neben wertvollem Wissen \u00fcber Start-ups und dem Ausprobieren unternehmerischen [&hellip;]<\/p>\n","protected":false},"author":295,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"features":[],"class_list":["post-1248","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jetzt anmelden zur ZHAW Startup Challenge 2020! - Entrepreneurship\u00ad@zhaw Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jetzt anmelden zur ZHAW Startup Challenge 2020!\" \/>\n<meta property=\"og:description\" content=\"Die ZHAW Startup Challenge geht 2020 in die sechste Runde! Bist du mit dabei? Ab sofort k\u00f6nnen sich unternehmerisch interessierte Studierende und Angeh\u00f6rige der gesamten ZHAW zur j\u00e4hrlichen Startup Challenge anmelden und erste Startup-Luft schnuppern. Eine Gelegenheit, die ihr euch auf keinen Fall entgehen lassen solltet. Neben wertvollem Wissen \u00fcber Start-ups und dem Ausprobieren unternehmerischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/\" \/>\n<meta property=\"og:site_name\" content=\"Entrepreneurship\u00ad@zhaw Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-15T09:35:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-15T11:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg\" \/>\n<meta name=\"author\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna-Maria Str\u00e4ssner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/\"},\"author\":{\"name\":\"Anna-Maria Str\u00e4ssner\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"headline\":\"Jetzt anmelden zur ZHAW Startup Challenge 2020!\",\"datePublished\":\"2020-01-15T09:35:57+00:00\",\"dateModified\":\"2020-01-15T11:55:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/\"},\"wordCount\":260,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2020\\\/01\\\/ZSC-Poster-791x1024.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/\",\"name\":\"Jetzt anmelden zur ZHAW Startup Challenge 2020! - Entrepreneurship\u00ad@zhaw Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2020\\\/01\\\/ZSC-Poster-791x1024.jpg\",\"datePublished\":\"2020-01-15T09:35:57+00:00\",\"dateModified\":\"2020-01-15T11:55:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2020\\\/01\\\/ZSC-Poster.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/files\\\/2020\\\/01\\\/ZSC-Poster.jpg\",\"width\":2550,\"height\":3300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/zhaw-startup-challenge-2020-es-geht-los\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jetzt anmelden zur ZHAW Startup Challenge 2020!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#website\",\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/\",\"name\":\"Entrepreneurship\u00ad@zhaw Blog\",\"description\":\"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/#\\\/schema\\\/person\\\/8ac961888822d6c253fc4aceba6e5323\",\"name\":\"Anna-Maria Str\u00e4ssner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g\",\"caption\":\"Anna-Maria Str\u00e4ssner\"},\"url\":\"https:\\\/\\\/blog.zhaw.ch\\\/entrepreneurship\\\/author\\\/stsn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jetzt anmelden zur ZHAW Startup Challenge 2020! - Entrepreneurship\u00ad@zhaw Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/","og_locale":"de_DE","og_type":"article","og_title":"Jetzt anmelden zur ZHAW Startup Challenge 2020!","og_description":"Die ZHAW Startup Challenge geht 2020 in die sechste Runde! Bist du mit dabei? Ab sofort k\u00f6nnen sich unternehmerisch interessierte Studierende und Angeh\u00f6rige der gesamten ZHAW zur j\u00e4hrlichen Startup Challenge anmelden und erste Startup-Luft schnuppern. Eine Gelegenheit, die ihr euch auf keinen Fall entgehen lassen solltet. Neben wertvollem Wissen \u00fcber Start-ups und dem Ausprobieren unternehmerischen [&hellip;]","og_url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/","og_site_name":"Entrepreneurship\u00ad@zhaw Blog","article_published_time":"2020-01-15T09:35:57+00:00","article_modified_time":"2020-01-15T11:55:06+00:00","og_image":[{"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg","type":"","width":"","height":""}],"author":"Anna-Maria Str\u00e4ssner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Anna-Maria Str\u00e4ssner","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#article","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/"},"author":{"name":"Anna-Maria Str\u00e4ssner","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"headline":"Jetzt anmelden zur ZHAW Startup Challenge 2020!","datePublished":"2020-01-15T09:35:57+00:00","dateModified":"2020-01-15T11:55:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/"},"wordCount":260,"commentCount":0,"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/","name":"Jetzt anmelden zur ZHAW Startup Challenge 2020! - Entrepreneurship\u00ad@zhaw Blog","isPartOf":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#primaryimage"},"image":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster-791x1024.jpg","datePublished":"2020-01-15T09:35:57+00:00","dateModified":"2020-01-15T11:55:06+00:00","author":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323"},"breadcrumb":{"@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#primaryimage","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster.jpg","contentUrl":"https:\/\/blog.zhaw.ch\/entrepreneurship\/files\/2020\/01\/ZSC-Poster.jpg","width":2550,"height":3300},{"@type":"BreadcrumbList","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/zhaw-startup-challenge-2020-es-geht-los\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.zhaw.ch\/entrepreneurship\/"},{"@type":"ListItem","position":2,"name":"Jetzt anmelden zur ZHAW Startup Challenge 2020!"}]},{"@type":"WebSite","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#website","url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/","name":"Entrepreneurship\u00ad@zhaw Blog","description":"Ein Blog der ZHAW Z\u00fcrcher Hochschule f\u00fcr Angewandte Wissenschaften","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.zhaw.ch\/entrepreneurship\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.zhaw.ch\/entrepreneurship\/#\/schema\/person\/8ac961888822d6c253fc4aceba6e5323","name":"Anna-Maria Str\u00e4ssner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422df26ad5d98eaa92b13e07734d66a9efacba5dc217e27afa634237a1d796ef?s=96&d=mm&r=g","caption":"Anna-Maria Str\u00e4ssner"},"url":"https:\/\/blog.zhaw.ch\/entrepreneurship\/author\/stsn\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/1248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/users\/295"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/comments?post=1248"}],"version-history":[{"count":2,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/1248\/revisions"}],"predecessor-version":[{"id":1252,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/posts\/1248\/revisions\/1252"}],"wp:attachment":[{"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/media?parent=1248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/categories?post=1248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/tags?post=1248"},{"taxonomy":"features","embeddable":true,"href":"https:\/\/blog.zhaw.ch\/entrepreneurship\/wp-json\/wp\/v2\/features?post=1248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}